{"id":58,"date":"2008-07-23T16:28:26","date_gmt":"2008-07-23T16:28:26","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sobreruedas\/?p=58"},"modified":"2008-07-23T16:28:26","modified_gmt":"2008-07-23T16:28:26","slug":"honda_ofrece_un_cheque_en_blanco_a_alons","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sobreruedas\/2008\/07\/23\/honda_ofrece_un_cheque_en_blanco_a_alons\/","title":{"rendered":"Honda ofrece un cheque en blanco a Alonso"},"content":{"rendered":"<p><DIV align=justify>La b\u00fasqueda por el mejor piloto posible libre para 2009 est\u00e1 abierta hace tiempo y los equipos siguen movi\u00e9ndose. M\u00e1s tarde entrar\u00e9 en detalles de los \u00faltimos movimientos entre los que destaca el del titular. Adem\u00e1s, comentar\u00e9&nbsp;otras de las noticias\/rumores que destacan en el mundillo de la <B>F<\/B><B>1 esta semana<\/B>.<\/DIV><br \/>\n<EMBED src=http:\/\/www.youtube.com\/v\/0uWYKQeahQM&#038;hl=en&#038;fs=1 width=425 height=344 type=application\/x-shockwave-flash allowfullscreen=\"true\"><\/EMBED><br \/>\n<DIV align=justify>&nbsp;<\/DIV><br \/>\n<DIV align=justify>Se ha hablado de que <B>Kovalainen dej\u00f3 pasar a Hamilton<\/B>. Est\u00e1 claro que lo hizo, \u00bfy qu\u00e9? En a\u00f1os anteriores hemos visto hacer lo mismo a Ferrari para beneficiar a Schumacher e incluso a Irvine cuando Schumacher estuvo lesionado y obligaron a Mika Salo a levantar el pie en Monza para dejar ganar a Irvine. Tambi\u00e9n se vio en Renault cuando Fisichella o Trulli ten\u00edan que facilitar el paso a Alonso cuando el asturiano se jugaba el Mundial. \u00bfA qu\u00e9 vienen estos comentarios? Probablemente a que el a\u00f1o pasado Hamilton no dejaba pasar a Alonso ni viceversa\u2026 pero claro, es que el a\u00f1o pasado se jugaban el Mundial entre ellos tambi\u00e9n y en la clasificaci\u00f3n general estaban apretados entre los dos y este a\u00f1o en Mc Laren la diferencia entre los dos pilotos es lo suficientemente amplia como para tener claro qui\u00e9n se jugar\u00e1 el t\u00edtulo por parte de este equipo. <B>Me pareci\u00f3 l\u00f3gica<\/B> la maniobra de Mc Laren y m\u00e1s cuando casi estropean la carrera del ingl\u00e9s. &nbsp;<\/DIV><br \/>\n<DIV align=justify>&nbsp;<\/DIV><br \/>\n<DIV align=justify>Parece que <B>Mc Laren<\/B> est\u00e1 usando un sistema de levas en el volante que permite a los pilotos utilizar distintos programas de curva de potencia de motor en momentos puntuales para regular la <B>forma de entrega de potencia<\/B> y as\u00ed salir de las curvas perdiendo menos tracci\u00f3n. Podr\u00eda ser uno de los secretos del \u00e9xito del MP4-23.<\/DIV><br \/>\n<DIV align=justify>&nbsp;<\/DIV><br \/>\n<DIV align=justify>Por otra parte <B>Webber<\/B> ha criticado el sistema actual de <B>safety car en la F1<\/B>, diciendo que \u201cver un resultado en el que un piloto que ha salido el 17\u00ba (<B>Piquet<\/B>) y casi termina ganando la carrera sin adelantar a nadie no es normal\u201d. Es cierto que no es normal, pero las carreras son as\u00ed, las normas son para todos y a veces te la juegas con la estrategia y te sonr\u00ede la fortuna y otras no. Hay muchas carreras que se ganan y se pierden por los accidentes y los coches de seguridad.<\/DIV><br \/>\n<DIV align=justify>&nbsp;<\/DIV><br \/>\n<DIV align=justify>En cuanto a este tema y sobre la carrera, <B>Josema y JM han dado buenas opiniones sobre el GP<\/B>&nbsp;en el post anterior (muchas gracias a ambos). He de hacer una <B>puntualizaci\u00f3n<\/B> de un asunto en cuanto a esto que se ha escrito de <B>Piquet<\/B>: \u201c<SPAN style=\"FONT-SIZE: 10pt; COLOR: #7a8891\">el aguantar varias vueltas en la posici\u00f3n que le ha regalado la suerte, sin ser presionado por nadie directamente (el siguiente estaba a 3 segundos) es lo m\u00ednimo que se le puede pedir a un piloto de Formula 1<SPAN style=\"FONT-SIZE: 8.5pt\">\u201d<\/SPAN><SPAN style=\"FONT-SIZE: 8.5pt\">. <\/SPAN><\/SPAN>Estoy de acuerdo en que esa posici\u00f3n se la regal\u00f3 la suerte en gran parte y en una peque\u00f1a parte el riesgo en tomar la estrategia que tom\u00f3. Pero <B>no fueron s\u00f3lo unas cuantas<\/B> vueltas las que aguant\u00f3 ah\u00ed. El safety car sali\u00f3 a pista en la vuelta 37 y la carrera se relanz\u00f3 en la vuelta 42. Desde la vuelta 42 hasta el final de la carrera en la 67 fueron 25 vueltas de carrera en las mismas condiciones de carga de carburante que Massa y Kovalainen (por ejemplo y entre muchos otros) que aprovecharon como \u00e9l el safety para repostar e ir hasta el final, aunque ellos por segunda vez saliendo por detr\u00e1s de Piquet. Aguantar como lo hizo tuvo su m\u00e9rito, <B>fueron 25 vueltas<\/B> con un coche inferior, sabiendo que por detr\u00e1s ven\u00edan un Ferrari, un BMW y un Mc Laren y que est\u00e1 tan en tela de juicio que en Francia se est\u00e1 empezando a hacer mucha presi\u00f3n para que un piloto del pa\u00eds de Renault (Romain Grosjean) ocupe su puesto en 2009 mediante continuas cr\u00edticas sobre su bajo rendimiento. Tuvo <B>much\u00edsima suerte, s\u00ed,<\/B> pero en mi opini\u00f3n <B>aguant\u00f3 muy bien<\/B>. &nbsp;&nbsp;<\/DIV><br \/>\n<DIV align=justify>&nbsp;<\/DIV><br \/>\n<DIV align=justify>En cuanto a los movimientos de esta \u00faltima semana, destaca que <B>Honda<\/B> en la que el reci\u00e9n llegado Ross Brawn tiene mucho peso habr\u00eda ofrecido un <B>cheque en blanco a Alonso por un contrato a largo plazo<\/B>. No les interesa Alonso para un a\u00f1o solamente, pero s\u00ed para intentar dar el salto definitivo de calidad en un plazo de varios a\u00f1os. Habr\u00e1 que ver qu\u00e9 ocurre con el tema Santander \u2013 Ferrari. Por su parte Renault le habr\u00eda pedido al asturiano una respuesta sobre su continuidad en el equipo para antes de septiembre. Por otro lado, adem\u00e1s del ya conocido fichaje de Vettel por Red Bull, Toro Rosso habr\u00eda ofrecido a Bourdais seguir en 2009. Por \u00faltimo y pese a que Raikkonen no dice nada sobre su futuro, se comenta que Ferrari le habr\u00eda propuesto renovar hasta 2011. <\/DIV><br \/>\n<DIV align=justify>&nbsp;<\/DIV><br \/>\n<DIV align=justify>Esta semana, los equipos entrenan en Jerez en condiciones de altas temperaturas similares a las que se encontrar\u00e1n en 10 d\u00edas en Hungaroring. En estos entrenamientos BMW estaba probando el sistema <B>KERS<\/B> (sistema de recuperaci\u00f3n de energ\u00eda para ser utilizada mediante un bot\u00f3n en el volante con el fin de obtener potencia extra durante un tiempo determinado) que quiere implantar la FIA a poder ser el pr\u00f3ximo a\u00f1o, y uno de sus mec\u00e1nicos al tocar el coche, ha sufrido un <B>chispazo<\/B> que lo ha tirado al suelo y que le ha provocado alguna quemadura en una mano y un brazo. Los equipos se van a reunir para tratar de mejorar la seguridad en la implantaci\u00f3n de este sistema que ya contaba con algunos esc\u00e9pticos.<\/DIV><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La b\u00fasqueda por el mejor piloto posible libre para 2009 est\u00e1 abierta hace tiempo y los equipos siguen movi\u00e9ndose. M\u00e1s tarde entrar\u00e9 en detalles de los \u00faltimos movimientos entre los que destaca el del titular. Adem\u00e1s, comentar\u00e9&nbsp;otras de las noticias\/rumores que destacan en el mundillo de la F1 esta semana. &nbsp; Se ha hablado de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[11],"class_list":["post-58","post","type-post","status-publish","format-standard","hentry","category-4","tag-1560_tag"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sobreruedas\/wp-json\/wp\/v2\/posts\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sobreruedas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sobreruedas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sobreruedas\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sobreruedas\/wp-json\/wp\/v2\/comments?post=58"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sobreruedas\/wp-json\/wp\/v2\/posts\/58\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sobreruedas\/wp-json\/wp\/v2\/media?parent=58"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sobreruedas\/wp-json\/wp\/v2\/categories?post=58"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sobreruedas\/wp-json\/wp\/v2\/tags?post=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}