{"id":1113,"date":"2012-06-18T07:56:20","date_gmt":"2012-06-18T06:56:20","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1113"},"modified":"2012-06-18T07:56:20","modified_gmt":"2012-06-18T06:56:20","slug":"vino-de-la-semana-edetana-2011","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2012\/06\/18\/vino-de-la-semana-edetana-2011\/","title":{"rendered":"Vino de la semana &#8211; Edetana 2011"},"content":{"rendered":"<p><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/06\/San-Sebasti%C3%A1n-20120618-00804.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1114\" title=\"San Sebasti\u00e1n-20120618-00804\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/06\/San-Sebasti%C3%A1n-20120618-00804-e1340002558557.jpg\" alt=\"\" width=\"225\" height=\"300\" \/><\/a>Llegas a la Terra Alta de Tarragona y empiezas a pensar en\u00a0 Iberos, Fenicios y curas con monaterios que se guardan detr\u00e1s de esos montes y valles para que nadie les tocara las narices ni los vi\u00f1edos que se tra\u00edan bajo la sotana para hacer conjuros que llamaban sacramentos y, por encima de todo, dinero. De eso trataban los Centros Comerciales de la \u00e9poca.<\/p>\n<p>Asi que tenemos un principio b\u00e1sico : se puede pensar en la zona de Tarragona como la primera en la que se vieron cepas en la pen\u00ednsula.\u00a0 Adelantando el video llegamos hasta el d\u00eda de hoy, lo uno por lo otro,\u00a0 gran zona para hacer grandes vinos. Y es en la Terra Alta de Tarragona donde se encuentran vinos diferentes, vinos que no se han masificado, bodegas peque\u00f1as,\u00a0 gentes particulares, personajes que se dedican a hacer vinos que un distribuidor definio como &#8220;vinos para hablar de vinos&#8221;.<\/p>\n<p>Este Edetana 2011,\u00a0 de la Bodega Edetaria,\u00a0 es un blanco fant\u00e1stico,\u00a0 de garnachas blancas de m\u00e1s de 70 a\u00f1os,\u00a0 con 4 meses fermentado en barrica, un vino serio que te gustar\u00eda tomar de entrada como un aperitivo de nivel con navajas, con mejillones serios o con unas gildas. Un vino que llevas m\u00e1s all\u00e1 y que puedes tomar con verduras o con un arroz cl\u00e1sico mediterr\u00e1neo y si te apetece llevarlo m\u00e1s all\u00e1,\u00a0 puedes acabar la comida con \u00e9l.<\/p>\n<p>Un vino que hace Joan Angel Lliberia hijo de viticultor, nieto de en\u00f3logo\u00a0 y esp\u00edritu de s\u00ed mismo que ha sabido darle personalidad a un proyecto que ha transmitido su personalidad a cadz botella y que nosotros. Nos podemos beber por unos 8 euros en Lukas (San Sebasti\u00e1n ). Ya nos vale buscar otros vinos blancos teniendo estos con tanta personalidad.<\/p>\n<p>@guiabuenamesa<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Llegas a la Terra Alta de Tarragona y empiezas a pensar en\u00a0 Iberos, Fenicios y curas con monaterios que se guardan detr\u00e1s de esos montes y valles para que nadie les tocara las narices ni los vi\u00f1edos que se tra\u00edan bajo la sotana para hacer conjuros que llamaban sacramentos y, por encima de todo, dinero. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1113","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1113"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1113\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}