{"id":1115,"date":"2012-06-20T07:50:25","date_gmt":"2012-06-20T06:50:25","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1115"},"modified":"2012-06-20T07:50:25","modified_gmt":"2012-06-20T06:50:25","slug":"kote-31-jovenes-y-atrevidos","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2012\/06\/20\/kote-31-jovenes-y-atrevidos\/","title":{"rendered":"Kota 31 &#8211; j\u00f3venes y atrevidos"},"content":{"rendered":"<p><strong id=\"internal-source-marker_0.3719771862961352\">Los hay en todas las disciplinas. Son j\u00f3venes con mucho talento a los que se les abre un brillante futuro. Normalmente est\u00e1n ah\u00ed para comerse el mundo, tienen criterios para hacer las cosas que hacen y tiran hacia adelante sin mirar atr\u00e1s, sin mirar ni a derecha ni a izquierda.<\/strong><\/p>\n<p>Y quienes escriben sobre la materia en la que est\u00e1n implicados tienen que andar siempre con mucha prudencia. Si les enalteces mucho y no dices lo que est\u00e1 mal, se lo pueden creer y pueden no darse cuenta de sus defectos, lo que normalmente se dice que se lo creen y no hay quien les tosa. Pero tampoco puedes darles un palo no vaya a ser que se desilusionen.<\/p>\n<p>\u00bfCu\u00e1ntos se quedan por el camino? \u00bfCu\u00e0ntos se cansan? \u00bfA cu\u00e0ntos se les agotan las ideas? \u00bfA cu\u00e1ntos les entra el p\u00e1nico? \u00bfCu\u00e1ntos se vuelven conformistas?<\/p>\n<p>Por eso me gustar\u00eda que este comentario fuera precavido, ni demasiado entusiasta, aunque a veces deber\u00eda serlo ni demasiado cr\u00edtico, aunque a veces deber\u00eda serlo.<\/p>\n<p>A Alvaro Verd\u00fa junto a Ramiro Garc\u00eda y Esti de la Fuente les ha unido el propietario del <a href=\"http:\/\/www.kota31.es\">Kota 31<\/a>, un local nuevo en la Parte Vieja donostiarra, para sacar adelante la cocina. La idea es presentar una oferta joven para llenar el local pero al mismo tiempo hay un hueco para quienes buscan algo diferente, hay producto de temporada, hay mucha calidad y hay un esfuerzo enorme por hacer las cosas bien. Estas son las cosas que gustaron:<\/p>\n<p><strong id=\"internal-source-marker_0.3719771862961352\"><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/06\/Anchoas1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1117\" title=\"Anchoas\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/06\/Anchoas1.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a><br \/>\nDe entrada anchoas de dos estilos, por un lado como se hace en B\u00e9rgamo (la influencia italiana que es de donde llega Alvaro se nota muy a menudo) con mantequilla y por otro naturales como la vida misma con una m\u00e1s que interesante salsa con cerveza negra, Jack Daniels y az\u00facar moscovado. Tiene que gustar por obligaci\u00f3n.<\/strong><\/p>\n<p><strong id=\"internal-source-marker_0.3719771862961352\"><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/06\/Tortilla-de-bacalao.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1118\" title=\"Tortilla de bacalao\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/06\/Tortilla-de-bacalao.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a><br \/>\nLa tortilla de bacalao en desconstrucci\u00f3n pero muy bien de textura y sabores, aut\u00e9ntica, no se pierde en la espuma, cierras los ojos y est\u00e1s en Roxario.<br \/>\n<a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/06\/Risotto.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1119\" title=\"Risotto\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/06\/Risotto.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a><br \/>\nRisotto a su manera es extra\u00f1o porque el arroz es tostado, si no se mide bien puede acabar pareciendo un desayuno, afortunadamente en este caso se acert\u00f3.<br \/>\n<a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/06\/Esparragos.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1120\" title=\"Esparragos\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/06\/Esparragos.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a><br \/>\nEsp\u00e1rragos en texturas, el acierto de trabajar con productos de temporada presentados de una manera atrevida. Hay vida m\u00e1s all\u00e1 de la verdura sin m\u00e1s.<br \/>\n<a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/06\/Pluma.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1121\" title=\"Pluma\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/06\/Pluma.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a><br \/>\nPluma de ib\u00e9rico con mascarpone y remolacha. Qu\u00e9 manera de acertar con la carne. Primero saber que no todo es ternera, vaca o carrillera en esta vida. La pluma es una gran pieza con mucho sabor y m\u00e1s a\u00fan si se presenta con la sencillez y el descaro con que lo presentan ellos. Con esa actitud es como se hace la cocina.<br \/>\n<a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/06\/Primer-postre.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1122\" title=\"Primer postre\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/06\/Primer-postre.jpg\" alt=\"\" width=\"300\" height=\"223\" \/><\/a><br \/>\nUn postre refescante con una base de cacao salado aunque sigo a la espera de esa tarta de queso que me prometen que me sorprender\u00e1.<\/strong><\/p>\n<p>Yo s\u00f3lo s\u00e9 que dos grandes chefs donostiarras (de los estrellados) les han visitado y han quedado prendados de su cocina. Y eso debe ser importante.<\/p>\n<p>La carta de vinos era floja floj\u00edsima al principio y ahora est\u00e1 empezando a depertar, nunca podr\u00e1 ser la mejor pero al menos ya hay referencias j\u00f3venes que les pueden representar, porque si la cocina es joven y atrevida, los vinos tambi\u00e9n deben serlo, aunque tambi\u00e9n haya cosas tradicionales y que gustan a todos el mundo, como es el caso del foie. La atenci\u00f3n es la que se espera en este tipo de lugares, cercana, amable y eficaz, incluso con un ingl\u00e9s perfecto.<\/p>\n<p>Lo importante ahora mismo es saber que hay gente descaradamente joven que est\u00e1 haciendo las cosas con sentido, que tienen la mirada puesta en lo esencial, saben de cocina y saben cocinar, tienen la t\u00e9cnica perfectamente ensayada y este es el momento en que les toca encontrar su personalidad, su estilo propio y van por el buen camino, ese camino que no es una autopista sino que tiene curvas y, si no tienes cuidado, te sales a la primera, tienes que saber frenar y acelerar a tiempo.<\/p>\n<p>Por cierto que por 25 euros tienes el men\u00fa degustaci\u00f3n al completo y merece la pena probarlo, si no, siempre quedan los pintxos.<\/p>\n<p>@guiabuenamesa<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Los hay en todas las disciplinas. Son j\u00f3venes con mucho talento a los que se les abre un brillante futuro. Normalmente est\u00e1n ah\u00ed para comerse el mundo, tienen criterios para hacer las cosas que hacen y tiran hacia adelante sin mirar atr\u00e1s, sin mirar ni a derecha ni a izquierda. Y quienes escriben sobre la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1115","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1115"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1115\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}