{"id":1154,"date":"2012-07-12T07:50:37","date_gmt":"2012-07-12T06:50:37","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1154"},"modified":"2012-07-12T07:50:37","modified_gmt":"2012-07-12T06:50:37","slug":"de-su-capa-un-sayo-pero-que-de-de-comer","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2012\/07\/12\/de-su-capa-un-sayo-pero-que-de-de-comer\/","title":{"rendered":"De su capa un sayo &#8211; pero que d\u00e9 de comer"},"content":{"rendered":"<p><strong id=\"internal-source-marker_0.31830896344035864\">Seguramente ser\u00e1 f\u00e1cil acordarse de la campa\u00f1a que ahora mismo est\u00e1 protagonizando Pau Gasol. Se trata de una campa\u00f1a solidaria bajo el lema \u201cNolotiro\u201d y en la que los restaurantes entregan a sus clientes una caja con las sobras de la comida que han hecho. Algo que aqu\u00ed no se estila mucho pero que por ah\u00ed es muy habitual, incluso lo llaman el \u201cdoggy bag\u201d , como quien dice la bolsa para el perro, un eufemismo que se ha encontrado para que no parezca que quieres comer al d\u00eda siguiente lo que no terminaste de zampar la noche anterior.<\/p>\n<p>Yukako Ichikawa se llama una chef japonesa en Sydney que lleva su historia m\u00e1s all\u00e1. Su restaurante se llama Wafu, muy ecol\u00f3gico y todo eso pero, sobre todo, muy responsable hasta el punto que te deja muy claro desde que haces la reserva que si no te traes tu propio \u201ccontenedor\u201d te pueden anular la mesa. La chef en concreto llama \u201cdesconsiderados\u201d a los clientes que no traen su propio doggy bag. Incluso llega al punto de decir que los clientes que declaran que est\u00e1n \u201cllenos\u201d cuando terminan de comer le producen stress, el motivo es porque han llegado al punto de da\u00f1ar su cuerpo para satisfacer su gula. Uno llamado Kazunori Nozawa en Los Angeles tambi\u00e9n echaba a patadas a quien no se comportara en su local, entioendo por no comportarse a sentarse de mala manera o a tener mal gusto para comer. Todo muy bonito si no fuera porque en ambos casos han cerrado sus negocios.<\/p>\n<p>Viene a cuento porque el propietario del local puede hacer lo que le venga en gana mientras pueda mantener su negocio abierto. Lo digo porque en los \u00faltimos d\u00edas he oido quejas, incluso de un renombrado cr\u00edtico, de que un restaurante en Madrid se sigue exigiendo chaqueta y corbata, en este caso concreto le hab\u00edan invitado a comer a dicho restaurante record\u00e1ndole el protocolo de dicho establecimiento a lo que el se\u00f1or twite\u00f3: \u201cAnacr\u00f3nico\u201d. Pero, por si acaso, fue a comer. \u00bfNo hubiera sido m\u00e1s sencillo no ir?<\/p>\n<p>Pueden poner las reglas de juego que quieran, somos los clientes lo que se las aceptamos o no y los que, al final, pagamos la cuenta que mantiene el local abierto.<\/p>\n<p>@guiabuenamesa<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Seguramente ser\u00e1 f\u00e1cil acordarse de la campa\u00f1a que ahora mismo est\u00e1 protagonizando Pau Gasol. Se trata de una campa\u00f1a solidaria bajo el lema \u201cNolotiro\u201d y en la que los restaurantes entregan a sus clientes una caja con las sobras de la comida que han hecho. Algo que aqu\u00ed no se estila mucho pero que por [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1154","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1154"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1154\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}