{"id":1156,"date":"2012-07-16T07:50:23","date_gmt":"2012-07-16T06:50:23","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1156"},"modified":"2012-07-16T07:50:23","modified_gmt":"2012-07-16T06:50:23","slug":"vino-de-la-semana-luna-beberide-gewuztrmainer-2011","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2012\/07\/16\/vino-de-la-semana-luna-beberide-gewuztrmainer-2011\/","title":{"rendered":"Vino de la semana &#8211; Luna Beberide Gewuztrmainer 2011"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong id=\"internal-source-marker_0.012056466192007065\"><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/07\/Luna2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1158\" title=\"Luna2\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/07\/Luna2-e1342418457760.jpg\" alt=\"\" width=\"237\" height=\"300\" \/><\/a><strong id=\"internal-source-marker_0.012056466192007065\">Los primeros recuerdos son importantes, sobre todo si son buenos. Muchas veces son la base sobre la que se van construyendo montones de nuevas sensaciones. En el mundo del vino esos primeros recuerdos tienen mucho que ver con las primeras uvas que te sorprenden, \u00a0las personas con que te tomas esos vinos, es as\u00ed de simple, ni siquiera tiene que haber grandes marcas ni botellas caras, ni siquiera sabes si el vino estaba realmente bueno o ten\u00eda defectos, solo sabes que aquello cambi\u00f3 muchas cosas y te emocionaste al mirarle a los ojos a la persona que ten\u00edas delante.<\/strong><\/strong><\/p>\n<p><strong id=\"internal-source-marker_0.012056466192007065\">Ocurri\u00f3 con un Gewuztraminer en Akelarre frente a M. La uva se qued\u00f3 para siempre en la memoria. Luego lleg\u00f3 el Somontano y Vi\u00f1as del Vero present\u00f3 lo que fue el mejor banco espa\u00f1\u00f1ol con solo dos a\u00f1os de vi\u00f1edo y era una Gewuztraminer, \u00a0y lo hac\u00eda un gran tipo, Pedro Aibar. Y despu\u00e9s un jovenc\u00edsimo Ra\u00fal P\u00e9rez lleg\u00f3 del Bierzo (\u00bfd\u00f3nde estaba el Bierzo entonces? ) y con toda su inocencia explic\u00f3 que hac\u00eda un vino de Gewuztraminer para los de casa. Lo present\u00f3 con precauci\u00f3n, \u00a0con la timidez de quien sabe que esta haciendo una travesura, el ni\u00f1o malo con una uva imposible, por eso mismo insist\u00eda en que era para los de casa, solopara los amigos, y nos lopresent\u00f3 y nos pareci\u00f3 una maravilla, realmente fuera de serie, pero ni siquiera pudimos comprar un par de botellas porque no se comercializaba.<\/strong><\/p>\n<p>Afortundamenre ha pasado el tiempo, hoy Ra\u00fal P\u00e9rez es un monstruo del mundo del vino que all\u00e1 donde pone su nombre pone el triunfo. Nadie le tose y nadie le discute (aunque a veces es bueno tener alguien en tu entorno que te recuerde que eres mortal) y si lo nuevo que hace es bueno, lo que ha hecho toda la vida es mejor.<\/p>\n<p>Asi que ahora comercializa el Gewuztraminer que un d\u00eda hac\u00eda para los suyos y ahora hace para todos. Y sigue siendo un paseo etre flores, descalzo en un campo de primvera, en una colina llena de aromas en las que se confunde la hierba, las flores y el an\u00eds, mucho an\u00eds al final, y encima te ves cogido de la mano de tu chica. Una estampa medio cursi, pero que te apetece recordar para siempre. Grande como todo lo que hace Ra\u00fal. En Super Amara.<\/p>\n<p>@guibuenamesa<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Los primeros recuerdos son importantes, sobre todo si son buenos. Muchas veces son la base sobre la que se van construyendo montones de nuevas sensaciones. En el mundo del vino esos primeros recuerdos tienen mucho que ver con las primeras uvas que te sorprenden, \u00a0las personas con que te tomas esos vinos, es as\u00ed [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1156","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1156"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1156\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}