{"id":1160,"date":"2012-07-18T07:50:45","date_gmt":"2012-07-18T06:50:45","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1160"},"modified":"2012-07-18T07:50:45","modified_gmt":"2012-07-18T06:50:45","slug":"vamos-a-contar-mentiras","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2012\/07\/18\/vamos-a-contar-mentiras\/","title":{"rendered":"Vamos a contar mentiras"},"content":{"rendered":"<p>A ver, que si hay que contarlas se cuentan, pero contarlas para nada no me parece bien.<\/p>\n<p>Esto es una persona americana que hace muchos a\u00f1os buscaba una fruta o verdura fuera de temporada y, como ha ocurrido durante mucho tiempo, no hab\u00eda precisamente porque estaba fuera de temporada. Y se extra\u00f1aba porque en la tierra de la abundancia ya hac\u00eda muchos a\u00f1os que hab\u00edan inventado aquello de que lo que si alguien busca un producto durante todo el a\u00f1o debe poder encontrarlo, sea por producci\u00f3n natural o artificial, lo importante es que haya.<\/p>\n<p>En el lado contrario el querido Roberto Ruiz con su \u00a0teor\u00eda de que las temporadas no son aburridas porque precisamente has esperado todo un a\u00f1o a que llegara un producto y \u00a1por fin! lo puedes consumir de nuevo en su estado \u00f3ptimo.<\/p>\n<p>Ya hay muchas cosas con las que vivimos de manera natural durante todo el a\u00f1o sin que nos preocupe mucho si son de temporada o no. Por poner un ejemplo sencillo y com\u00fan: el tomate.<br \/>\nSin preguntas y, encima, capaces de pensar que en alg\u00fan lugar donde lo sirven durante todo el a\u00f1o resulta que es \u201cel mejor tomate que no has probado otro igual.\u201d Que as\u00ed sea. Al fin y al cabo es un producto de consumo masivo y a un precio razonable si te apetece.<\/p>\n<p>Pero mucho da\u00f1o le estar\u00e1n haciendo a alg\u00fan otro producto por su precio prohibitivo si lo siguen sirviendo fuera de temporada como si fuera de temporada. Hace ya m\u00e1s de un mes, casi dos, un gran cocinero me sirvi\u00f3 unos guisantitos al grito de \u201clos \u00faltimos de la temporada\u201d al menos eso le hab\u00edan dicho a \u00e9l. Al d\u00eda siguiente le tuve que llamar para decirle que, efectivamente, eran los \u00faltimos porque no me volv\u00eda a ver en su restaurante, tan malos estaban. Y dos semanas despu\u00e9s tuve que soportar a otro amigo y gran cocinero que se empe\u00f1\u00f3 en poner unos guisantitos que al ver mi cara de extra\u00f1eza comprobando que est\u00e1bamos en verano me dec\u00eda: \u201crevientan en la boca\u201d. En la boca y en la cara, es probable que reventaran, pero el sabor se hab\u00eda ido en el reventado. He llegado a probar experimentos en invierno y se pod\u00eda hacer harina con aquellos.<\/p>\n<p>Lo \u00fanico que puede ocurrir si siguen con estos experimentos (o congelados) es que al final se consiga lo que quiere la mayor\u00eda, que tengan un precio razonable para todos, de acuerdo, pero entonces que nadie se queje cuando se empiece a decir \u201cpero es que ya no saben a nada, los de antes s\u00ed que estaban buenos.\u201d<\/p>\n<p>@guiabuenamesa<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>A ver, que si hay que contarlas se cuentan, pero contarlas para nada no me parece bien. Esto es una persona americana que hace muchos a\u00f1os buscaba una fruta o verdura fuera de temporada y, como ha ocurrido durante mucho tiempo, no hab\u00eda precisamente porque estaba fuera de temporada. Y se extra\u00f1aba porque en la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1160","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1160"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1160\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}