{"id":1233,"date":"2012-09-10T07:55:45","date_gmt":"2012-09-10T06:55:45","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1233"},"modified":"2012-09-10T07:55:45","modified_gmt":"2012-09-10T06:55:45","slug":"vino-de-la-semana-la-mar-de-terras-gauda","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2012\/09\/10\/vino-de-la-semana-la-mar-de-terras-gauda\/","title":{"rendered":"Vino de la semana &#8211; La Mar de Terras Gauda"},"content":{"rendered":"<p><strong id=\"internal-source-marker_0.9526118459179997\"><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/09\/La-Mar.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1234\" title=\"La Mar\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/09\/La-Mar-e1347259248656.jpg\" alt=\"\" width=\"177\" height=\"300\" \/><\/a>Acabo de probar un vino incre\u00edble. Para empezar dice Rias Baixas y casi ni te lo crees. Pero es que, adem\u00e1s, dice Terras Gauda y a\u00fan te lo crees menos. A ver, si no digo yo que en Terras Gauda no hagan grandes vinos, que los hacen y es m\u00e1s, es una bodega seria que ha sabido poner los vinos gallegos en el mapa. Cuando nadie sab\u00eda casi c\u00f3mo se hac\u00eda buen vino en Galicia, est\u00e1 bodega se fund\u00f3 con el claro objetivo de hacer vinos de alta calidad. En el a\u00f1o 90 empezaron a demostrar que Galicia iba a tener un puesto de honor en el mercado del vino. Precisamente por eso, porque llevan tantos a\u00f1os haci\u00e9ndolo bien que ya das por supuesto que no te vana sorpender.<\/p>\n<p>En O Rosal decidieron sacar lo mejor de la tierra y se propusieron, no solo, a hacer vino sino a investigar en las variedades aut\u00f3ctonas con diferentes clones de la albari\u00f1o y, adem\u00e1s a darle importancia a la Cai\u00f1o Blanco y a la Loureiro. Fruto de todo ese trabajo es este La Mar de Terras Gauda, Rias Baixas pero con la particularidad de que es la Cai\u00f1o Blanco la que protagoniza el vino lo que le da un car\u00e1cter tan especial, diferente y yo dir\u00eda que incluso distinguido.<\/p>\n<p>Manzanilla, melocot\u00f3n pero ese melocot\u00f3n maduro, rico, carnoso y una manzanilla , fresca arom\u00e1tica. Hay m\u00e1s fruta blanca como la pera, pero lo que m\u00e1s entretiene de este vino su paso por boca, esa manera de ser fresca pero a la vez elegante, como si conocieras a un joven de la alta sociedad que no sea empalagoso. Una entrada f\u00e1cil puede que sea porque se ha mantenido sobre l\u00edas y luego ha descansado antes de presentarse en p\u00fablico, esa acidez de lo gallego, esa locura se ha asentado. Lo dicho, un vino incre\u00edble.<\/p>\n<p>En twitter: @guiabuenamesa<br \/>\n<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Acabo de probar un vino incre\u00edble. Para empezar dice Rias Baixas y casi ni te lo crees. Pero es que, adem\u00e1s, dice Terras Gauda y a\u00fan te lo crees menos. A ver, si no digo yo que en Terras Gauda no hagan grandes vinos, que los hacen y es m\u00e1s, es una bodega seria que [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1233","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1233"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1233\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}