{"id":1280,"date":"2012-09-20T07:50:32","date_gmt":"2012-09-20T06:50:32","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1280"},"modified":"2012-09-20T07:50:32","modified_gmt":"2012-09-20T06:50:32","slug":"las-sensaciones-del-comer","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2012\/09\/20\/las-sensaciones-del-comer\/","title":{"rendered":"Las sensaciones del comer"},"content":{"rendered":"<p>El Video se ve <a href=\"http:\/\/http:\/\/www.eitb.com\/es\/videos\/detalle\/950434\/video-gastronomia--cena-virtual-basque-culinary-center\/\">aqu\u00ed<\/a><\/p>\n<p><strong id=\"internal-source-marker_0.8840392753481865\">Salgo en las fotos y en el v\u00eddeo y se me hace extra\u00f1o no comentar las sensaciones de esta idea que se les ha ocurrido a&#8230;. esa especie de Think Tank del BCC y que pone en marcha la tecnolog\u00eda m\u00e1s actual y la comida.<\/p>\n<p>Se trata de hacer que diversas tecnolog\u00edas intervengan en la experiencia del comer. V\u00eddeos, c\u00e1maras, luces, pantallas interactivas, todo para vivir la experiencia de una cena\/comida de una manera diferente, integral, te ves metido dentro de un halo que te absorbe y te hace uno con todo lo que te rodea.<\/p>\n<p>Como experiencia vale, como curiosidad vale, pero a mi, que me han dado el t\u00edtulo de gastrosaurio me permiten hacer varias estos comentarios.<\/p>\n<p>Es un paso m\u00e1s a la iluminaci\u00f3n de un local, a la decoraci\u00f3n, al ambiente, a la horrorosa m\u00fasica de fondo, incluso al vestuario de los camareros, s\u00ed, es un paso m\u00e1s, la pregunta es d\u00f3nde ponemos el l\u00edmite si es que hay que ponerlo. Porque no quiero que haya una serie de cosas que interfieran en la comida que estoy haciendo, ni con la compa\u00f1\u00eda con la que estoy, si la conversaci\u00f3n en la mesa es. \u201cMira qu\u00e9 paisaje de montes que es donde pastan las ovejitas que nos vamos a comer\u201d o \u201cf\u00edjate c\u00f3mo se mueven las luces cuando muevo el plato\u201d, en lugar de \u201cQu\u00e9 ojos tan preciosos tienes hoy\u201d pues prefiero que no me conecten.<\/p>\n<p>Incluso la interactividad con la cocina (puedes ver a los cocineros en las pantallas y, probablemente, ellos te puedan ver a ti y tus gestos seg\u00fan comas los platos), es un paso m\u00e1s de las cocinas abiertas y la pregunta final si te ha gustado el plato. Seguimos haciendo la pregunta \u00bfd\u00f3nde ponemos el l\u00edmite? Sabiendo c\u00f3mo son los cocineros y ese peque\u00f1o ego que les acompa\u00f1a y les atormenta no creo que sea una buena idea que te vean poner cara de asco en alg\u00fan plato.<\/p>\n<p>Los experimentos est\u00e1n muy bien porque siempre habr\u00e1 alguna conclusi\u00f3n que se pueda sacar pero, qu\u00e9 quieren que les diga, la verdadera sensaci\u00f3n debe estar en el plato, los aromas que despiertan la imaginaci\u00f3n, cada bocado que sabe distinto precisamente porque tu pones de tus experiencias propias. Y cada momento es irrepetible. \u00bfAcaso nadie ha visto el Fest\u00edn de Babette? Habr\u00eda que empezar por ah\u00ed para darse cuenta de c\u00f3mo debe ser la experiencia del comer.<\/strong><\/p>\n<p>En twitter: @guiabuenamesa<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El Video se ve aqu\u00ed Salgo en las fotos y en el v\u00eddeo y se me hace extra\u00f1o no comentar las sensaciones de esta idea que se les ha ocurrido a&#8230;. esa especie de Think Tank del BCC y que pone en marcha la tecnolog\u00eda m\u00e1s actual y la comida. Se trata de hacer que [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1280","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1280"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1280\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}