{"id":1312,"date":"2012-10-18T08:56:38","date_gmt":"2012-10-18T07:56:38","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1312"},"modified":"2012-10-18T08:56:38","modified_gmt":"2012-10-18T07:56:38","slug":"esos-vinos-diferentes-irekonductibles","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2012\/10\/18\/esos-vinos-diferentes-irekonductibles\/","title":{"rendered":"Esos vinos diferentes &#8211; iRekonductibles"},"content":{"rendered":"<p><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/10\/iRekonductibles-octubre-12.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1313\" title=\"iRekonductibles octubre 12\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/10\/iRekonductibles-octubre-12-e1350546930103.jpg\" alt=\"\" width=\"300\" height=\"255\" \/><\/a><\/p>\n<p>Una de las mejores cosas que tiene el mundo del vino es su diversidad. \u00bfPor qu\u00e9 quedarte siempre con el mismo vino si puedes variar tanto y tan bueno? Siempre he pensado que en la variedad est\u00e1 el gusto.<\/p>\n<p>Estando as\u00ed las cosas, lo que tambi\u00e9n sorprende es que puedas seguir encontrando vinos tan diferentes en toda Espa\u00f1a y eso siempre es una buena noticia. Parec\u00eda que la uva menc\u00eda del Bierzo ya hab\u00eda dado todo lo que ten\u00eda que dar de s\u00ed, hay algunos bodegueros que est\u00e1n haciendo las cosas bien y que le est\u00e1n dando a esa uva, que hace 15 a\u00f1os no conoc\u00edamos, la importancia que se merece hasta el punto de que se ha convertido en una estrella.<\/p>\n<p>Y, adem\u00e1s, hay otros locos que se dedican a rescatar tierras olvidadas, cepas centenarias y a plantar variedades extra\u00f1as hasta el punto de podernos demostrar que en el Bierzo se puede hacer de todo y todo ser\u00e1 diferente. Uno de esos locos es Gabriel Merayo, un hombre que se march\u00f3 con 17 a\u00f1os de la zona y que ha vuelto afortunadamente para hacer vinos tan diferentes que te descolocan totalmente. Cepas m\u00e1s que centenarias de menc\u00eda y otras de GARNACHA TINTORERA, algo extraordinario, dan unos vinos que muchos especialistas no sabr\u00edan colocar, te llevan por todo el panorama de los grandes vinos, incluyendo Borgo\u00f1a. Hay mucha pasi\u00f3n detr\u00e1s de esos vinos y se nota a la hora de llev\u00e1rtelos a la boca.<\/p>\n<p>Pero es que, adem\u00e1s, ha plantado sauvignon blanc y gewuztraminer que marcan claramente la diferencia entre un estilo de vinos blancos y otros. Nada parecido a lo que se suele pensar que son esas variedades, hay m\u00e1s intensidad, m\u00e1s seriedad, donde otros vinos son tropicales y florales de manera que te empalagan aqu\u00ed todo es m\u00e1s profundo y elegante, no hay nada que te canse. L\u00e1stima que el mercado siga pidiendo porquer\u00edas a un euro porque har\u00e1 que el bueno de Gabriel se canse y deje que las uvas caigan a la nada.<\/p>\n<p>Vi\u00f1a Albares se llama la bodega que nos dej\u00f3 a los iRekonductibles clavados a los asientos, es una bodega joven pero se merece todos los respetos porque pone en el mercado vinos diferentes y a eso hemos venido.<\/p>\n<p>En twitter: @guiabuenamesa<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Una de las mejores cosas que tiene el mundo del vino es su diversidad. \u00bfPor qu\u00e9 quedarte siempre con el mismo vino si puedes variar tanto y tan bueno? Siempre he pensado que en la variedad est\u00e1 el gusto. Estando as\u00ed las cosas, lo que tambi\u00e9n sorprende es que puedas seguir encontrando vinos tan diferentes [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1312","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1312"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1312\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}