{"id":1437,"date":"2012-12-24T08:50:09","date_gmt":"2012-12-24T07:50:09","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1437"},"modified":"2012-12-24T08:50:09","modified_gmt":"2012-12-24T07:50:09","slug":"vino-de-la-semana-muga-flor-nueva","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2012\/12\/24\/vino-de-la-semana-muga-flor-nueva\/","title":{"rendered":"Vino de la semana &#8211; Muga Flor Nueva"},"content":{"rendered":"<p><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/12\/Muga1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-1439\" title=\"Muga\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2012\/12\/Muga1.jpg\" alt=\"\" width=\"108\" height=\"302\" \/><\/a>En la \u00e9poca en la que estamos quiero dar a conocer un vino solidario. <a href=\"http:\/\/www.bodegasmuga.com\">Bodegas Muga<\/a> y la Fundaci\u00f3n Cuentasue\u00f1os se han embarcado en un proyecto para llevar agua a 6.500 personas en los barrios perif\u00e9ricos de Adis Abeba, la capital de Etiop\u00eda.<\/p>\n<p>El vino se llama Flor Nueva (que en et\u00edope es Adis Abeba) y para formar parte del proyecto solidario tienes que hacerte socio de &#8220;El club de los 300&#8221;. Hacerte socio es sencillo y productivo porque la inscripci\u00f3n son 6 botellas de esta Flor Nueva de Bodegas Muga, un vino diferente y \u00fanico porque lleva esas otras variedades riojanas que completan otros vinos y que en este caso hacen que el car\u00e1cter de este vino sea muy diferente. Mazuelo, graciano y garnacha son la base principal, tempranillo y maturana son las variedades que completan el vino. As\u00ed que es riojano pero como lo es de antes, con mucha personalidad, un vino del 2010 que est\u00e1 para beber ya, pero que aguantar\u00e1 un mont\u00f3n de a\u00f1os, para ir probando una botella al a\u00f1o y recordar todas las nochebuenas la obra que se ha hecho.<\/p>\n<p>El precio de la caja\/inscripci\u00f3n en El club de los 300 es de 180 euros, a 30 eurillos la botella que es un precio extraordinario porque este vino es de los que podr\u00edas calcular por 60. Intervienen todos los que han formado el vino: corcho (Cork Supply), las etiquetas (Industrias Gr\u00e1ficas Marcal), embalaje (Estucher\u00edas Vargas) y hasta el transporte a casa gracias a Seur.<\/p>\n<p>As\u00ed que si te has propuesto ser bueno e intervenir en una causa solidaria pero que lo que te gusta es el vino, el serio, el de de verdad, esta es propuesta es muy buena. Las inscripciones se hacen en la p\u00e1gina web de la bodega.<\/p>\n<p>En twitter: @guiabuenamesa<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En la \u00e9poca en la que estamos quiero dar a conocer un vino solidario. Bodegas Muga y la Fundaci\u00f3n Cuentasue\u00f1os se han embarcado en un proyecto para llevar agua a 6.500 personas en los barrios perif\u00e9ricos de Adis Abeba, la capital de Etiop\u00eda. El vino se llama Flor Nueva (que en et\u00edope es Adis Abeba) [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1437","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1437"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1437\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}