{"id":1483,"date":"2013-02-14T08:50:21","date_gmt":"2013-02-14T07:50:21","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1483"},"modified":"2013-02-14T08:50:21","modified_gmt":"2013-02-14T07:50:21","slug":"que-tienes-en-contra-de-san-valentin","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2013\/02\/14\/que-tienes-en-contra-de-san-valentin\/","title":{"rendered":"\u00bfQu\u00e9 tienes en contra de San Valent\u00edn?"},"content":{"rendered":"<p>En serio, \u00bfqu\u00e9 te pasa?<\/p>\n<p>\u00bfPor qu\u00e9 te quejas de las promociones del d\u00eda de San Valent\u00edn?<\/p>\n<p>\u00bfAcaso eres demasiado mayor para entenderlas?<\/p>\n<p>\u00bfNo se supone que trabajas en el mundo de la gastronom\u00eda y que debes entender a los hosteleros?<\/p>\n<p>Veamos, el d\u00eda de San Valent\u00edn deber\u00eda ser uno de los d\u00edas de mayores pesadillas para los hosteleros. S\u00f3lo salen parejas y llenan el restaurante con mesas de dos,\u00a0 que dejan pocos m\u00e1rgenes y te las ves y te las deseas para crear un poco de intimidad en el espacio que hay. Hasta tal punto que en algunos restaurantes anglosajones (por esos paises es el d\u00eda m\u00e1s fuerte pero el m\u00e1s pu\u00f1etero porque encima tienes que hacer como si no conocieras a ese cliente habitual que viene casi siempre con una rubia y que ahora te enteras que no es su mujer) optan por hacer mesas corridas suponiendo que cada pareja s\u00f3lo mirar\u00e1 de frente a su media naranja.<\/p>\n<p>Pero tambi\u00e9n es un poco de aire fresco en el mes de febrero que suele ser de los peores para la facturaci\u00f3n anual. Un mes de fr\u00edo y lluvia con pocas ganas de salir y que se encuentra con esta fecha en medio de la nada, s\u00ed, para algunos es respirar a mediados de mes cuando ya te hund\u00edas en el barro.<\/p>\n<p>As\u00ed que no pasa nada. Hoy es el d\u00eda de San Valent\u00edn y recomiendo que se aproveche todo el mundo de las promociones que hay en todas partes, que busque y que escoja el que m\u00e1s le paetezca o que cree el suyo propio. Para un d\u00eda que el amor es oficial salid a descubrirlo y adecirle a alguien que le quieres y que no puedes vivir sin ella, \u00e9l o lo que sea&#8230; Por cierto, que seguro que las promociones se alargan hasta el fin de semana.<\/p>\n<p>En twitter: @guiabuenamesa<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En serio, \u00bfqu\u00e9 te pasa? \u00bfPor qu\u00e9 te quejas de las promociones del d\u00eda de San Valent\u00edn? \u00bfAcaso eres demasiado mayor para entenderlas? \u00bfNo se supone que trabajas en el mundo de la gastronom\u00eda y que debes entender a los hosteleros? Veamos, el d\u00eda de San Valent\u00edn deber\u00eda ser uno de los d\u00edas de mayores [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1483","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1483"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1483\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}