{"id":1493,"date":"2013-02-22T08:52:10","date_gmt":"2013-02-22T07:52:10","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1493"},"modified":"2013-02-22T08:52:10","modified_gmt":"2013-02-22T07:52:10","slug":"el-kir-royale-de-aqui","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2013\/02\/22\/el-kir-royale-de-aqui\/","title":{"rendered":"El Kir Royale de aqu\u00ed"},"content":{"rendered":"<p><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/02\/Kir-royale.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1494\" title=\"Kir royale\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/02\/Kir-royale.jpg\" alt=\"\" width=\"92\" height=\"300\" \/><\/a><a>Sacerdote tuvo que ser ser el inventor del famoso cocktail. Sencillo donde los haya y refrescante. Empez\u00f3 siendo un Kir normal de vino blanco y cassis para pasar a ser Royale con champagne y cassis, casi casi mezclados al gusto para dar lugar a un rompehielos ideal (como cocktail de bienvenidad), refrescante y encima con el nombre de &#8220;royale&#8221; que siempre da prestancia. <\/a><\/p>\n<p><a>As\u00ed que est\u00e1bamos en una cata de pacharanes y no hab\u00eda duda, porque al final el cassis es un licor de una grosella negra (una baya) macerada en alcohol y el pachar\u00e1n no deja de ser una endrina (otra baya) macerada en alcohol con an\u00eds. \u00bfPor qu\u00e9 no? Nos dijimos \u00bfpor qu\u00e9 no podemos hacer un cassis m\u00e1s de aqu\u00ed? Cava y pachar\u00e1n. Y all\u00e1 que nos lanzamos. Y no estuvo mal, hasta Pepe Dioni, maestro de cockteleros, le dio el visto bueno.<br \/>\n<\/a><\/p>\n<p><a>El kir naci\u00f3 con la idea de dar salida a dos productos de una zona, la borgo\u00f1a francesa (por lo del vino y el cassis), as\u00ed que la historia se escribe con ideas de promoci\u00f3n brillantes y, sobre todo, la importancia de lo sencillo, es de esos cocktails que se pueden hacer en casa en cualquier momento. Seguro que habr\u00e1 alguna botella de pachar\u00e1n perdida y habr\u00e1 quedado la botella de cava de navidades, as\u00ed que cuando lleguen los familiares y\/o amigos a casa antes de la comida o cena preparad el kir este m\u00e1s de aqu\u00ed y que disfruten que para eso est\u00e1 la vida. <\/a><\/p>\n<p>Lo que s\u00ed habr\u00e1 que hacer es buscarle un nombre decente.<\/p>\n<p><a>En twitter: @guiabuenamesa <\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Sacerdote tuvo que ser ser el inventor del famoso cocktail. Sencillo donde los haya y refrescante. Empez\u00f3 siendo un Kir normal de vino blanco y cassis para pasar a ser Royale con champagne y cassis, casi casi mezclados al gusto para dar lugar a un rompehielos ideal (como cocktail de bienvenidad), refrescante y encima con [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1493","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1493"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1493\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}