{"id":1518,"date":"2013-03-12T08:50:09","date_gmt":"2013-03-12T07:50:09","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1518"},"modified":"2013-03-12T08:50:09","modified_gmt":"2013-03-12T07:50:09","slug":"tu-eres-artesano-o-cocinero-creativo-dialogos-de-cocina-refelxiones-1","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2013\/03\/12\/tu-eres-artesano-o-cocinero-creativo-dialogos-de-cocina-refelxiones-1\/","title":{"rendered":"\u00bfTu eres artesano o cocinero &#8211; creativo? &#8211; Di\u00e1logos de cocina refelxiones 1"},"content":{"rendered":"<p>Este a\u00f1o los &#8220;Di\u00e1logos de cocina 2013&#8221; se dedican al concepto de la artesan\u00eda. Me imagino que por un doble motivo: por un lado la necesidad que tienen los cocineros de hacerse entender como unos artesanos, aunque sean modernos. Y por otro lado porque hay una tendencia a defender a los artesanos de una manera casi casi como una necesidad frente los tiempos en los que la burocracia y las normas demasiado estrictas pueden hacer que perdamos el norte y el sentido com\u00fan.<\/p>\n<p>En realidad sobre el primer tema estoy un poco hasta las marices. Que si el cocienro es artesano o no ya me la trae al pairo. Yo lo que quiero es que quien est\u00e9 en una cocina me cocine un plato que me satisfaga. Que hay muchos artesanos que hacen cosas horribles que vemos en un mont\u00f3n de ferias de artesan\u00eda y hay artistas que acaban por hacer piezas industriales en serie que gustan mucho y satisfacen (y no me refiero a Nacho Vidal).<\/p>\n<p>Y en eso que lleg\u00f3 Ignacio Morgade y dijo unas cosas que parec\u00edan muy sensatas: &#8220;La arertsan\u00eda est\u00e1 tanto en las ideas como en la ejecuci\u00f3n.&#8221;\u00a0 Ven\u00eda a decir que hay artesan\u00eda detr\u00e1s de las obras manuales hechas mec\u00e1nicamente. Pero precisamente en esas obras el artesano es capaz de poner cari\u00f1o y ese cari\u00f1o es lo que le lleva a ser creativo. Por eso mismo, el hecho de que un chef haga la cocina con cari\u00f1o le lleva a ser creativo<\/p>\n<p>As\u00ed que esa relaci\u00f3n entre lo artesano y lo creativo parece clara. El alba\u00f1il o el carpintero primero fueron artesanos y luego fueron creativos e incluso construyeron casas. Y siglos m\u00e1s tarde alguien decidi\u00f3 que estudiaran carreras y se llamaran arquitectos. Pero enotnces existe el peligro de que pasen a creerse creativos sin haber sido artesanos y entonces pasa lo de Calatrava (que s\u00ed, que ya s\u00e9 que es Ingeniero, pero el caso es que nunca ha sido artesano) o lo del Arquitecto que hace un edificio con errores hasta para vivir en ellos.<\/p>\n<p>A lo que voy: esto del Basque Culinary Center \u00bfnos dar\u00e1 cocineros que no hayan pasado por ser artesanos y nos dar\u00e1 directamente creativos? Nunca hay que perder la perspectiva de la artesan\u00eda de la cocina..<\/p>\n<p>&nbsp;<\/p>\n<p>Del otro motivo hablamos ma\u00f1ana si es que merece la pena.<\/p>\n<p>Por cierto, que una de las caracter\u00edsticas m\u00e1s visuales de un artesano suele ser la uniformidad, ese traje que, m\u00e1s o menos les distingue, y \u00bfpor qu\u00e9 ser\u00e1 que a estos artesanos tan modernos se les ense\u00f1a a todos a no llevar la gorra? Es una pregunta para abrir un di\u00e1logo, sin m\u00e1s.<\/p>\n<p>&nbsp;<\/p>\n<p>En twitter: @guiabuenamesa<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Este a\u00f1o los &#8220;Di\u00e1logos de cocina 2013&#8221; se dedican al concepto de la artesan\u00eda. Me imagino que por un doble motivo: por un lado la necesidad que tienen los cocineros de hacerse entender como unos artesanos, aunque sean modernos. Y por otro lado porque hay una tendencia a defender a los artesanos de una manera [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1518","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1518"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1518\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}