{"id":1544,"date":"2013-03-25T08:50:25","date_gmt":"2013-03-25T07:50:25","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1544"},"modified":"2013-03-25T08:50:25","modified_gmt":"2013-03-25T07:50:25","slug":"vino-de-la-semana-recaredo-2007","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2013\/03\/25\/vino-de-la-semana-recaredo-2007\/","title":{"rendered":"Vino de la semana &#8211; Recaredo 2007"},"content":{"rendered":"<p><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/03\/DSC_0379-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1545\" title=\"DSC_0379-1\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/03\/DSC_0379-1.jpg\" alt=\"\" width=\"180\" height=\"300\" \/><\/a>Mientras los franceses discuten si deben poner o no la fecha de deg\u00fcelle en las botellas de champagne los cavistas andan a la gre\u00f1a sobre el euro que debe costar la botella. Menos mal que se empeizan a distinguir los buenos, los grandes productores, de los que s\u00f3lo buscan hacer mercado por el precio.<\/p>\n<p>Los buenos hace tiempo que tomaron la decisi\u00f3n de la calidad por encima de todo, y han empezado por poner la a\u00f1ada en la etiqueta de sus cavas, conscientes de que a quienes les gusta el cava de verdad saben que una a\u00f1ada es el s\u00edmbolo de un vino bien hecho, un vino de calidad que mejora en botella despu\u00e9s de haber pasado sus buenos meses en la bodega.<\/p>\n<p>Recaredo es uno de ellos. Fue el primer gran cava que entr\u00f3 en mi vida hace ya muchos a\u00f1os, en el momento en que pasas del de supermercado porque buscas algo m\u00e1s y te encuentras con cavas del estilo de REcaredo y te abren un mundo nuevo. Baj\u00f3 un poco a finales de los 90 y ha vuelto a coger la senda de los m\u00e1s grandes. Y aqu\u00ed est\u00e1 con este Brut Nature 2007 y no te da miedo cogerlo porque primero sabes que detr\u00e1s hay una serie de gente joven que apuesta por las cosas bien hechas que detr\u00e1s hay una viticultura cuidada de sus propios vi\u00f1edos, sabes que hay una parte que fermenta en barrica que le da un car\u00e1cter diferente al cava, y que hay una serie de pasos cuidados, como por ejemplo que el deg\u00fcelle se hace sin congelar la punta de la botella.<\/p>\n<p>Un cava para gozar de mucha fruta blanca y un toque amielado que ir\u00e1 creciendo con los a\u00f1os (yo no lo ver\u00e9 porque pienso tomarme cada botella que caiga en mis manos), sobre todo es un cava graso que entra facilmente en boca y tiene un final que no s\u00f3lo te invita a beber m\u00e1s sino que sabes que es perfecto para una gastronom\u00eda de alto nivel porque no te cansa la boca con az\u00facares falsos. Brut Nature como debe ser.<\/p>\n<p>A 16 eruos en Lukas (Donostia) es un chollo que deber\u00eda desaparecer de las estanter\u00edas. Aunque quiz\u00e1s no lo repito mucho porque quiero m\u00e1s.<\/p>\n<p>En twitter: @guiabuenamesa<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Mientras los franceses discuten si deben poner o no la fecha de deg\u00fcelle en las botellas de champagne los cavistas andan a la gre\u00f1a sobre el euro que debe costar la botella. Menos mal que se empeizan a distinguir los buenos, los grandes productores, de los que s\u00f3lo buscan hacer mercado por el precio. Los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1544","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1544"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1544\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}