{"id":1546,"date":"2013-03-26T08:50:54","date_gmt":"2013-03-26T07:50:54","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1546"},"modified":"2013-03-26T08:50:54","modified_gmt":"2013-03-26T07:50:54","slug":"casa-marcial-algo-falla-en-los-dos-estrellas","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2013\/03\/26\/casa-marcial-algo-falla-en-los-dos-estrellas\/","title":{"rendered":"Casa Marcial &#8211; algo falla en los dos estrellas"},"content":{"rendered":"<p>Hay un s\u00edndrome de las dos estrellas que afecta a un mont\u00f3n de cocineros y restaurantes. Luchan durante a\u00f1os para que se les reconozca elesfuerzo y la creatividad a trav\u00e9s de las estrellas y, cuando alcanzan la segunda pasan unos a\u00f1os de dudas. A\u00f1os en los que est\u00e1n intentando ser m\u00e1s creativos que nadie, quieren epatar en todos los congresos, se sienten en otro mundo y lo tienen que demostrar. La pena es que muchos se quedan estancados. S\u00ed, hay grandes platos en sus men\u00fas degustaci\u00f3n, pero hay otros que no alcanzan el aprobado. Muchas de las comidas se convierten en viajes en una monta\u00f1a rusa. Grandes momentos al lado de otros incomprensibles. Alargan el men\u00fa en un intento por rizar el rizo y, como los toreros que han alcanzado un status, alargan las faenas sin ning\u00fan sentido por ver si alg\u00fan pase es glorioso y muchas veces lo \u00fanico que sale glorioso es el precio.<\/p>\n<p>Por eso\u00a0 cuando uno sale de un dos estrellas totalmente satisfecho con todos y cada uno de los platos que ha tomado en el men\u00fa degustaci\u00f3n merece la pena que se diga a los cuatro vientos. Y si encima el men\u00fa ha costado 69 euros merece la pena incluso aplaudir a rabiar. <a href=\"http:\/\/www.casamarcial.com\">Casa Marcial<\/a> con Nacho Manzano al frente es uno de esos momentos m\u00e1gicos que uno encuentra y que no se espera. Literalmente donde alguien perdi\u00f3 el mechero, en la punta del monte all\u00e1 en Arriondas (Asturias), en una casa a la que no te acercar\u00edas si no fuera porque te han dicho que se come bien, se encuentra la casa familiar de la familia Manzano donde desde hace un montonazo de a\u00f1os alguien decidi\u00f3 que el hijo de la familia cocinaba muy bien y que le daban una oportunidad de sacar adelante un restaurante. Y vaya que si lo ha conseguido.Su cocina se define de una manera muy sencilla porque es muy directa. Es una cocina que se entiende, que huye de las complicaciones, lo ves, sabes lo que es y te lo comes. No hace falta m\u00e1s. Claro que es f\u00e1cil cuando pides un men\u00fa m\u00e1s tradicional, pero es cuando se nota al verdadero cocinero, sin complejos de moderneces, ah\u00ed es cuando se notan los elementos de la vanguardia que hacen que el camino de la tradici\u00f3n est\u00e9 m\u00e1s iluminado, sea m\u00e1s fresco, la vanguardia se nota en la mano,\u00a0 en los detalles, el plato es la esencia, la mano del cocinero es el paisaje, si el cuadro no est\u00e1 distorsionado entonces se nota la genialidad. Hay muchos que intentan hacer cuadros impecables y les salen muchos borrones. Aqu\u00ed todo encaja.<\/p>\n<p>El men\u00fa completo:<\/p>\n<p>Gazpacho ajoblanco<\/p>\n<p><a href=\"http:\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/03\/1-gazpacho.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"1 gazpacho\" src=\"\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/03\/1-gazpacho-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a><\/p>\n<p>Oricio con holandesa (muy ligera) acidulada y arom\u00e1ticos sobre yogur. Un plato casi perfecto en el que destaca todo el potente sabor del oricio con esos toques tan cl\u00e1sicos de una salsa imposible como la holandesa.<\/p>\n<p><a href=\"http:\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/03\/2-Oricio.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"2 Oricio\" src=\"\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/03\/2-Oricio-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a><\/p>\n<p>Callos de bacalao con lentejas al comino, caldo de verduras a la brasa, pil &#8211; pil ligero y cebolleta. Brillante en todos sus sabores que se ayudan entre s\u00ed. TExtura dif\u00edcil y sin embargo llevadero gracias a las lentejas que contrastan con los callos.<\/p>\n<p><a href=\"http:\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/03\/4-liebre.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"3 Callos\" src=\"\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/03\/3-Callos-e1364250542538-224x300.jpg\" alt=\"\" width=\"224\" height=\"300\" \/><\/a><\/p>\n<p>Liebre en suave royal con matices frutales. Me parece el plato por excelencia en el que un cocinero demuestra que lo es.<\/p>\n<p><a href=\"http:\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/03\/4-liebre1.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"4 liebre\" src=\"\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/03\/4-liebre1-e1364250704968-288x300.jpg\" alt=\"\" width=\"288\" height=\"300\" \/><\/a><\/p>\n<p>Pitu de caleya guisado al estilo de mi madre con ravioli de sus menudillos. Ya se ve de d\u00f3nde le viene la mano a Nacho Manzano. Y esos raviolis todav\u00eda est\u00e1n en la memoria.<\/p>\n<p><a href=\"http:\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/03\/5-pitu.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"5 pitu\" src=\"\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/03\/5-pitu-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a><\/p>\n<p>Y crema de maiz con helado de trufa y agua de manzana<\/p>\n<p><a href=\"http:\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/03\/6-2-crema.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"6 2 crema\" src=\"\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/03\/6-2-crema-e1364250892423-300x282.jpg\" alt=\"\" width=\"300\" height=\"282\" \/><\/a><\/p>\n<p>Unos cuantos postres ligeros cubrieron todo el men\u00fa.<\/p>\n<p>La sala es otro de los jardines en los que los dos estrellas se suelen meter. De tener una sala relajada al mismo tiempo que precisa y bien llevada, en cuanto a algunos les dan un par de estrellas y se vuelven serios, tensos, se ponen estupendos y no puedes ni toser. Aqu\u00ed no, se ve que es una sala que se sigue haciendo en el mismo tono familiar que siempre se ha hecho. El comedor es peque\u00f1o, coqueto y la casa est\u00e1 bien dise\u00f1ada. Lo lleva Sandra Manzano, hermana de Nacho (las otras dos hermanas llevan el nuevo local de Gij\u00f3n) y el sumiller murciano Juan Luis Garc\u00eda que, como debe ser, no se echa atr\u00e1s al recomendar vinos locales, aunque Asturias no sea tradicionalmente tierra de vinos \u00e9l sabe lo que tiene entre manos y lo recomienda. Gracias a eso pudimos probar un m\u00e1s que recomendable Dominio del Urogallo Retortoiro 2011 un biodin\u00e1mico de Cangas de Narcea con fruta y mineralidad, perfectamente equilibrado. La sorpresa que es lo que se busca cuando uno se pone en manos de un sumiller y no quiere lo cl\u00e1sico.<\/p>\n<p>Es uno de esos lugares al que apetece volver todos los a\u00f1os por seguirle el rastro.<\/p>\n<p>Como siempre, el titular para despistar: Algo falla en los dos estrellas, no es este el caso.<\/p>\n<p>&nbsp;<\/p>\n<p>En twitter: @guiabuenamesa<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hay un s\u00edndrome de las dos estrellas que afecta a un mont\u00f3n de cocineros y restaurantes. Luchan durante a\u00f1os para que se les reconozca elesfuerzo y la creatividad a trav\u00e9s de las estrellas y, cuando alcanzan la segunda pasan unos a\u00f1os de dudas. A\u00f1os en los que est\u00e1n intentando ser m\u00e1s creativos que nadie, quieren [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1546","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1546"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1546\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}