{"id":1559,"date":"2013-04-09T09:10:19","date_gmt":"2013-04-09T08:10:19","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1559"},"modified":"2013-04-09T09:10:19","modified_gmt":"2013-04-09T08:10:19","slug":"los-jovenes-salvaran-al-vino-irekonductibles","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2013\/04\/09\/los-jovenes-salvaran-al-vino-irekonductibles\/","title":{"rendered":"Los j\u00f3venes salvar\u00e1n al vino &#8211; iRekonductibles"},"content":{"rendered":"<p>Para que luego digan que no quieren dedicarse al campo y sus labores. Quiz\u00e1s sea cierto que sus padres tuvieron que sacar adelante una vida m\u00e1s dura, quiz\u00e1s sea porque gracias a que sus padres plantaron unos vi\u00f1edos con mayor rendimiento y m\u00e1s posibilidades de facturar ellos ahora pueden dedicarse a un mundo del vino m\u00e1s reconocido y m\u00e1s glamuroso, si es que s epuede llamar glamour a pasarse horas entre vi\u00f1as, recuperando zonas olvidadas y cepas perdidas, si se puede llamar glamour a horas de carretera, a meter la mano en la tierra a cualquier temperatura, a un tractor y luego tener que promocionar tu mismo tus vinos porque eres el que los ha visto nacer, realmente quien los entiende y nadie puede hablar de tus hijos mejor que tu.<\/p>\n<p>El hecho es que hay una serie de j\u00f3venes que hoy en d\u00eda se est\u00e1n dedicando muy en serio a esto de hacer vinos que hoy sorprenden y que tienen ganas de que, alg\u00fan d\u00eda, lleguen a ser grandes vinos.<\/p>\n<p>David Sampedro se llama uno de ellos, un joven de El Villar y que se ha empe\u00f1ado en hacer vinos que llaman la atenci\u00f3n por muchos motivos. Busca la autenticidad y eso ya es un punto fundamental, hace vinos como los que se hac\u00edan antes en la Rioja en donde de una misma finca se sacaba toda la uva y se hac\u00eda un vino y ya est\u00e1, busca cepas perdidas en todas partes (la Rufete es un ejemplo), desde Valencia hasta Salamanca e incluso busca la manera de hacer vinos nuevos y diferentes que no est\u00e1n en la cabeza de nadie (un moscatel con viura asombroso con baja graduaci\u00f3n). Hace vinos para BEBER. Y, adem\u00e1s, es divertido con los nombres de sus vinos: La Malkerida, Pasolasmonjas, Phincas, Terca, El Durmiente o El Novio.<\/p>\n<p>Pero hay una cosa por la que destacan estos j\u00f3venes y es su respeto por todo lo bueno que se hizo antes, no quieren romper con el pasado sino que quieren tenerlo como una inspiraci\u00f3n para su trabajo. As\u00ed que despu\u00e9s de divertirse con nosotros y una cata a ciegas en la que, salvo honrosas y discretas excepciones, no conseguimos situar los vinos ni geogr\u00e1ficamente, despu\u00e9s de que nos sorprendi\u00e9ramos todos con una cata preciosa nos pusimos a revisar el pasado y, entre peqeu\u00f1as joyas, descubrimos un Cepa Oro de Bodegas Bilbainas del 60 que estaba espectacular bajo todos los criterios y como regalo final abrimos media botella del Imperial del 41.<\/p>\n<p><a href=\"http:\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/04\/DSC_0395-13.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"DSC_0395-1\" src=\"\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/04\/DSC_0395-13-172x300.jpg\" alt=\"\" width=\"172\" height=\"300\" \/><\/a><a href=\"http:\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/04\/DSC_0399-1.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"DSC_0399-1\" src=\"\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/04\/DSC_0399-1-141x300.jpg\" alt=\"\" width=\"141\" height=\"300\" \/><\/a><\/p>\n<p>No digo m\u00e1s que David Sampedro se llev\u00f3 esas dos botellas, vac\u00edas, con la firma de Txomin para guardarlas como un recuerdo \u00fanico de unos vinos que son un ejemplo y con la ilusi\u00f3n de que dentro de 30 o 40 a\u00f1os otros j\u00f3venes abran unos vinos llamados La Malkerida, Pasolasmonjas, Phincas&#8230;<\/p>\n<p><a href=\"http:\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/04\/DSC_0396-11.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"DSC_0396-1\" src=\"\/\/www.guiadelabuenamesa.es\/wp-content\/uploads\/2013\/04\/DSC_0396-11-300x153.jpg\" alt=\"\" width=\"300\" height=\"153\" \/><\/a><\/p>\n<p>En twitter: @guiabuenamesa<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Para que luego digan que no quieren dedicarse al campo y sus labores. Quiz\u00e1s sea cierto que sus padres tuvieron que sacar adelante una vida m\u00e1s dura, quiz\u00e1s sea porque gracias a que sus padres plantaron unos vi\u00f1edos con mayor rendimiento y m\u00e1s posibilidades de facturar ellos ahora pueden dedicarse a un mundo del vino [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1559","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1559"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1559\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}