{"id":1610,"date":"2013-05-08T07:49:35","date_gmt":"2013-05-08T06:49:35","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1610"},"modified":"2013-05-08T07:49:35","modified_gmt":"2013-05-08T06:49:35","slug":"el-sol-sale-por-la-montanera-en-donosti","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2013\/05\/08\/el-sol-sale-por-la-montanera-en-donosti\/","title":{"rendered":"El sol sale por la montanera en Donosti"},"content":{"rendered":"<p>La montanera es esa \u00e9poca en la que los cerdos ib\u00e9ricos van al monte a comer solamente lo que encuentran con el hocico. Normalmente es lo que cae de los \u00e1rboles que se encuentran por los alrededores, bellotas y hierba. En el Pa\u00eds de Quercus lo saben muy bien porque bajo esa marca Carlos Tristancho deja a sus cerdos hacer la montanera y s\u00f3lo cuando han coigdo un peso concreto, es decir, cuando han engordado 6 arrobas, los saca para su sacrificio. Todo lo que dan esos cerdos es pura maravilla, lujo y sabor a lo aut\u00e9ntico.<\/p>\n<p><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/05\/Montanera-cartel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1611\" title=\"Montanera cartel\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/05\/Montanera-cartel.jpg\" alt=\"\" width=\"300\" height=\"170\" \/><\/a><\/p>\n<p>La noticia es que ahora en la Parte Vieja de San Sebasti\u00e1n, en la calle 31 de Agosto, se pueden encontrar todos los productos del Pais de Quercus en un nuevo\/viejo bar llamado <a href=\"http:\/\/www.kota31.es\">La Montanera by Kota 31<\/a>. El bar tuvo su fama ef\u00edmera, apost\u00e9 por los cocineros j\u00f3venes que hac\u00edan una cocina interesante hasta donde pudieron. El equipo de disolvi\u00f3 y como buenos j\u00f3venes que son cada uno campea a sus anchas, desde Madrid hasta Londres junto a Arzak. As\u00ed que los propietarios han apostado por algo mucho m\u00e1s s\u00f3lido y reconocible. Bajo el nombre de La Montanera y una decoraci\u00f3n muy kitsch del sur ofrecen los embutidos del Pais de Quercus a un precio lo suficientemente razonable como para que se pueda probar. El lomo, el jam\u00f3n son los cl\u00e1sicos extraordinarios pero es que el chorizo y, por encima de todo, el salchich\u00f3n son excepcionales. \u00bfPor qu\u00e9 considera la gente que el salchich\u00f3n es una pieza menor? Hay quien sabe hacerlo con piezas de lujo del cerdo y puede ser untuoso y con mucho sabor.<\/p>\n<p><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/05\/Montanera-ibericos.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1612\" title=\"Montanera ibericos\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/05\/Montanera-ibericos.jpg\" alt=\"\" width=\"300\" height=\"224\" \/><\/a><\/p>\n<p>Pero la cocina no s elimita a eso porque la maravilla es que se han decidido por una cocina muy casera, platos reconocibles y reconocidos, platos de cuchara sencillos y esas manitas de cordero que no se encuentran en muchos sitios (por no decir en ninguno en la Parte Vieja) y que est\u00e1n de chuparse los dedos a la vez que te los comes.<\/p>\n<p><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/05\/Montanera-manitas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1613\" title=\"Montanera manitas\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/05\/Montanera-manitas.jpg\" alt=\"\" width=\"300\" height=\"224\" \/><\/a><\/p>\n<p>Merece la pena el paseo por La Montanera y m\u00e1s merecer\u00e1 en cuanto se pongan las pilas con el vino que siempre ha sido una asignatura pendiente y que se resolver\u00e1 en cuesti\u00f3n de d\u00edas.<\/p>\n<p>En twitter: @guiabuenamesa<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La montanera es esa \u00e9poca en la que los cerdos ib\u00e9ricos van al monte a comer solamente lo que encuentran con el hocico. Normalmente es lo que cae de los \u00e1rboles que se encuentran por los alrededores, bellotas y hierba. En el Pa\u00eds de Quercus lo saben muy bien porque bajo esa marca Carlos Tristancho [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1610","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1610"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1610\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}