{"id":1641,"date":"2013-05-30T07:50:29","date_gmt":"2013-05-30T06:50:29","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1641"},"modified":"2013-05-30T07:50:29","modified_gmt":"2013-05-30T06:50:29","slug":"de-verdad-merece-la-pena-rioja","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2013\/05\/30\/de-verdad-merece-la-pena-rioja\/","title":{"rendered":"\u00bfDe verdad merece la pena, Rioja?"},"content":{"rendered":"<p><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/05\/Rioja1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1643\" title=\"Rioja\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/05\/Rioja1.jpg\" alt=\"\" width=\"300\" height=\"270\" \/><\/a><\/p>\n<p>No soy de los que creen en las DOs a pies juntillas. Es m\u00e1s, a veces creo que se pasan en hacer cantidad de tonter\u00edas. He visto de todo. Los he visto ponerse como &#8220;locos&#8221; porque un bodeguero presentaba un vino de una uva permitida pero como monovarietal, &#8220;s\u00f3lo est\u00e1 permitido en un porcentaje peque\u00f1o&#8221; dec\u00eda el inspector, &#8220;no lo puedes presentar como monovarietal&#8221;. \u00bfY qu\u00e9? Si la permites, d\u00e9ja en paz a la bodega hacer lo que quiera.<\/p>\n<p>Algunas bodegas catalanas han resuelto sus problemas sali\u00e9ndose de la DO cava y haciendo una propia. He conocido bodegueros que dec\u00edan que estaban con la DO s\u00f3lo por poder poner la contraetiqueta porque vend\u00eda m\u00e1s.<\/p>\n<p>Viene a cuento porque la DO de La Rioja acaba de permitir dos variedades de uva blanca for\u00e1nea entrar en los vi\u00f1edos de la zona. Los vinos blancos son los que realemente est\u00e1n teniendo un subid\u00f3n de ventas en los \u00faltimos a\u00f1os (alguien que haya seguido este blog desde sus inicios sabr\u00e1 que aqu\u00ed siempre hemos hablado bien de los blancos y de las posibilidades que tienen) as\u00ed que la DO Rioja ha decidido apoyar a las bodegas permitiendo dos variedades que, se supone, venden m\u00e1s en mercados internacionales. La verdejo y la chardonnay creen que aportar\u00e1n mejoras a sus vinos.<\/p>\n<p>Y me acuerdo de los a\u00f1os en los que Rueda permiti\u00f3 la Sauvignon Blanc, hasta el 100%, para mejorar las ventas, se supon\u00eda que la verdejo era una uva imposible, \u00e1cida, sin aromas y que no se llevaba bien con nadie. Eso pensaban hasta que llegaron de fuera quienes supieron darle su valor real. La verdejo es una de las grandes hoy en d\u00eda si se le sabe tratar bien y sacarle todo el partido. Hoy la DO Rueda se muere de asco con precios rid\u00edculos que no permiten ni pagar la escuela p\u00fablica de los cr\u00edos, venden lo que sea al precio que sea y hay mucha morralla. Hay productores que siguen defendiendo la verdejo y la quieren vender al precio que se merece y no pueden. Se ha llegado al punto rid\u00edculo en los bares en los que si pides un Rueda te preguntan si quieres verdejo o Rueda, como si alguien que pide un crianza le preguntaran &#8220;\u00bfqu\u00e9 quiere, tempranillo o Rioja?&#8221;<\/p>\n<p>Y por si no han aprendido la lecci\u00f3n los de Rioja van y dan el paso. Ahora permitir\u00e1n plantar la verdejo y chardonnay. Y no es que est\u00e9 en contra de las uvas for\u00e1neas de por s\u00ed. D\u00f3nde estar\u00eda La Rioja si no fuera por la tempranillo que ya se ha convertido en ciudadano de hecho. Seguramente los vinos tendr\u00edan m\u00e1s personalidad pero los riojanos ser\u00edan m\u00e1s pobres. Pero es que la viura, es mucha viura, es una de las grandes capaz de hacer vinos que perduran en el tiempo. Probablemente sea realmente la uva que encontraron los franceses cuando les toc\u00f3 la filoxera. La viura es la base del m\u00e1s grande de los vinos blancos del mundo, el Gran Reserva de Vi\u00f1a Tondonia y he probado un vino blanco de 1913 que a\u00fan estaba vivo. Y m\u00e1s a\u00fan, con el gran Basilio Izquierdo pudimos probar los blancos que hac\u00eda y fueron brillantes, hechos con garnacha blanca de pura cepa riojana.<\/p>\n<p>Ya s\u00e9 que, de momento, no son muchas hect\u00e1reas pero me pregunto: \u00bfDe verdad que merece la pena, Rioja? Con tanto y tan bueno que hay. Para vender m\u00e1s y mejor de lo que se trata es que se hagan bien las cosas y nada m\u00e1s, con personalidad de la tierra y nada m\u00e1s.<\/p>\n<p>En twitter: @guiabuenamesa<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>No soy de los que creen en las DOs a pies juntillas. Es m\u00e1s, a veces creo que se pasan en hacer cantidad de tonter\u00edas. He visto de todo. Los he visto ponerse como &#8220;locos&#8221; porque un bodeguero presentaba un vino de una uva permitida pero como monovarietal, &#8220;s\u00f3lo est\u00e1 permitido en un porcentaje peque\u00f1o&#8221; [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1641","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1641"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1641\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}