{"id":1651,"date":"2013-06-10T07:59:18","date_gmt":"2013-06-10T06:59:18","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1651"},"modified":"2013-06-10T07:59:18","modified_gmt":"2013-06-10T06:59:18","slug":"vino-de-la-semana-marques-de-caceres-rosado","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2013\/06\/10\/vino-de-la-semana-marques-de-caceres-rosado\/","title":{"rendered":"Vino de la semana &#8211; Marqu\u00e9s de C\u00e1ceres Rosado"},"content":{"rendered":"<p><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/06\/Marques.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1652\" title=\"Marques\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/06\/Marques.jpg\" alt=\"\" width=\"102\" height=\"300\" \/><\/a>Recuerdos. Recuerdos de una tarde de verano. Recuerdos de cenas en pareja. Recuerdos de miradas, de restaurantes, de conversaciones antes que de aromas y sabores.<\/p>\n<p>Y entre esos recuerdos hay una marca que destaca. Porque cuando no ten\u00edas ni edad ni parecer ped\u00edas lo que hab\u00eda que pedir. Te pon\u00edan un par de marcas por delante y un d\u00eda ped\u00edas una y otro d\u00eda ped\u00edas otra, y como sal\u00edas a cenar de vez en cuando pues ibas coincidiendo con un vino y con otro.<\/p>\n<p>Marqu\u00e9s de C\u00e1ceres era uno de los amigos que te acompa\u00f1aba en cada mirada, los buenos recuerdos los rodeaban copas de este vino rosado y entonces no te dabas cuenta de lo que ten\u00edas entre manos y ahora sabes que si se vend\u00eda tanto este rosado era porque era uno de los mejores rosados que se pod\u00eda tomar en una \u00e9poca concreta de vinos mediocres y tristes.<\/p>\n<p>Este rosado de Marqu\u00e9s de C\u00e1ceres ya forma parte de tu vida y, adem\u00e1s, es fant\u00e1stico porque da unas notas de fruta fresca amorosa, porque es tempranillo m\u00e1s garnacha, como si fuera fruta sobre fruta, es complejo y divertido, es como un comic de Grumble que acaba por gustarte porque s\u00ed. Y voy a contar un secreto: sacarlo de la cubitera porque un poco m\u00e1s caliente el vino es un aut\u00e9ntico lujo, se vuelve maduro e interesante, es Grumble m\u00e1s mayor. Un vino que se pone entre los rosados mas grandes para el verano que llegar\u00e1 y en torno de los 5 eurillos.<\/p>\n<p>En twitter: @guiabuenamesa<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Recuerdos. Recuerdos de una tarde de verano. Recuerdos de cenas en pareja. Recuerdos de miradas, de restaurantes, de conversaciones antes que de aromas y sabores. Y entre esos recuerdos hay una marca que destaca. Porque cuando no ten\u00edas ni edad ni parecer ped\u00edas lo que hab\u00eda que pedir. Te pon\u00edan un par de marcas por [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1651","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1651"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1651\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}