{"id":1708,"date":"2013-08-12T10:23:19","date_gmt":"2013-08-12T09:23:19","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1708"},"modified":"2013-08-12T10:23:19","modified_gmt":"2013-08-12T09:23:19","slug":"vino-de-la-semana-phincas-09","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2013\/08\/12\/vino-de-la-semana-phincas-09\/","title":{"rendered":"Vino de la semana &#8211; Phincas 09"},"content":{"rendered":"<p><a href=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/08\/Phyncas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1709\" title=\"Phyncas\" src=\"\/sopadeganso\/wp-content\/uploads\/sites\/18\/2013\/08\/Phyncas.jpg\" alt=\"\" width=\"110\" height=\"300\" \/><\/a>Cuentan los m\u00e1s viejos del lugar que antiguamente, muy antiguamente, los agricultores, que hoy se llaman viticultores, hac\u00edan sus vinos tal que as\u00ed. Entraban en el vi\u00f1edo, en su finca, cuando consideraban que era oportuno, recog\u00edan lo que hab\u00eda y el vino se hac\u00eda. No hab\u00eda t\u00e9cnicos, no hab\u00eda en\u00f3logos, \u00a0y, por no haber, no hab\u00eda gente rara hablando de vinos, como yo. Hab\u00eda lugare\u00f1os que hac\u00edan vino y se hac\u00eda perfectamente.<\/p>\n<p>M\u00e1s a\u00fan, no hab\u00eda denominaciones de origen que obligaran a unas uvas concretas, no hab\u00eda etiquetas en las que tuvieran que poner 100% tempranillo o lo que fuera. Nadie preguntaba: \u00bfqu\u00e9 variedades lleva? A nadie le importaba, si el vino estaba bueno se compraba y se acab\u00f3. En Francia a nadie le importa qu\u00e9 uvas entran en un determinado vino y, al fin y al cabo, ellos algo saben de eso.<\/p>\n<p>De esa filosof\u00eda, de esa tradici\u00f3n tan sincera de hacer vinos sin tapujos nace este Phincas y David Sampedro es su responsable.<\/p>\n<p>David Sampedro es un joven vinatero, un joven que sabe hacer vinos de verdad, vinos que saben a vino y a tradici\u00f3n, un joven al que le gusta jugar con las variedades y que nos est\u00e1 dando un mont\u00f3n de alegr\u00edas a pesar de ser tan joven. \u00a0Ha encontrado una parcela en La Rioja donde se mezclan un mont\u00f3n de variedades, graciano, tempranillo, garnacha y viura entre otras porque seguro que habr\u00e1 alguna otra cosa rara, las ha recogido cuando ha llegado la hora, todas al mismo tiempo, y ha hecho uno de los vinos riojanos que se recordar\u00e1n.<\/p>\n<p>Este 09 es muy frutal y muy fresco, la madera le ha acariciado al vino y por eso no se nota casi nada, pero seguro que lo suficiente para que el vino aguante a\u00f1os, l\u00e1stima que no podremos saberlo porque nos lo bebemos todo hoy. Merece la pena si se quiere saber lo que es el vino de verdad.<\/p>\n<p>En twitter: @guiabuenamesa<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Cuentan los m\u00e1s viejos del lugar que antiguamente, muy antiguamente, los agricultores, que hoy se llaman viticultores, hac\u00edan sus vinos tal que as\u00ed. Entraban en el vi\u00f1edo, en su finca, cuando consideraban que era oportuno, recog\u00edan lo que hab\u00eda y el vino se hac\u00eda. No hab\u00eda t\u00e9cnicos, no hab\u00eda en\u00f3logos, \u00a0y, por no haber, no [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1708","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1708"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1708\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}