{"id":1794,"date":"2013-10-14T07:32:03","date_gmt":"2013-10-14T06:32:03","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sopadeganso\/?p=1794"},"modified":"2013-10-14T07:32:03","modified_gmt":"2013-10-14T06:32:03","slug":"guiabuenamesa-debe-morir","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sopadeganso\/2013\/10\/14\/guiabuenamesa-debe-morir\/","title":{"rendered":"@guiabuenamesa debe morir"},"content":{"rendered":"<p>Hace ya m\u00e1s de una semana que twitter ha bloqueado mi cuenta. Piensan que alguien ha hackeado mi cuenta o que alguien ha intentado entrar en ella sin mi permiso. Me pregunto a qui\u00e9n le puede interesar algo as\u00ed, pero la realidad es esta.<\/p>\n<p>Desde entonces no he podido escribir media l\u00ednea aunque la cuenta sigue viva y ah\u00ed est\u00e1n mis seguidores. Pero a la vista de que los se\u00f1ores de twitter no me devuelven mi cuenta a pesar de todos los escritos que les he enviado y sus promesas de enviarme un correo con una nueva contrase\u00f1a para poder entrar en mi cuenta, he tomado la decisi\u00f3n de asesinar (virtualmente se entiende) la cuenta @guiabuenamesa y trasladarme mi vida a otra cuenta: @igalatas &#8211; que soy yo y es m\u00e1s comprensible.<\/p>\n<p>As\u00ed que desde hoy vuelvo a nacer en otra vida y espero sobrepasar los seguidores que ya hab\u00eda conseguido a lo largo de este tiempo en twitter, buena gente que me sigue por lo que digo y retwiteo que s\u00f3lo pretende hacer que la gente pase un buen rato con esto del buen vivir y algo de publicidad que es mi otra pasi\u00f3n.<\/p>\n<p>As\u00ed que ya se sabe, fieles seguidores a partir de hoy estar\u00e9 en twitter: @igalatas<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hace ya m\u00e1s de una semana que twitter ha bloqueado mi cuenta. Piensan que alguien ha hackeado mi cuenta o que alguien ha intentado entrar en ella sin mi permiso. Me pregunto a qui\u00e9n le puede interesar algo as\u00ed, pero la realidad es esta. Desde entonces no he podido escribir media l\u00ednea aunque la cuenta [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1794","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/comments?post=1794"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/posts\/1794\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/media?parent=1794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/categories?post=1794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sopadeganso\/wp-json\/wp\/v2\/tags?post=1794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}