{"id":182,"date":"2013-12-21T23:38:07","date_gmt":"2013-12-21T22:38:07","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sukaldatu\/?p=182"},"modified":"2013-12-21T23:38:07","modified_gmt":"2013-12-21T22:38:07","slug":"en-estas-navidades-turron-de-chocolate-casero","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sukaldatu\/2013\/12\/21\/en-estas-navidades-turron-de-chocolate-casero\/","title":{"rendered":"En estas navidades turr\u00f3n de chocolate casero"},"content":{"rendered":"<p>Para mi las navidades son cocina, familia y amigos. Imagino que cuando a uno le gusta algo, como me pasa a mi con la cocina, quiere disfrutar de ello\u00a0y m\u00e1s cuando es para compartir con los que m\u00e1s quieres. A veces tengo mis serias dudas de que cocinar a destajo sea una satisfacci\u00f3n, las dudas me entran despu\u00e9s de llevar varias horas entre horno, pucheros y masas. Me planteo poner la cama en la cocina, paso en ella m\u00e1s tiempo que en cualquier otra parte. Cada a\u00f1o a\u00f1ado un grado de dificultad, me meto en unos fregados serios yo solita, as\u00ed que no puedo echarle la culpa a nadie. Estos d\u00edas ando rodeada de polvorones y turrones, aunque est\u00e9 cansada me gusta pensar que estar\u00e1n en muchas casas en estas cenas y comidas tan &#8220;especiales&#8221;. Adem\u00e1s de lo agradecida que estoy de que haya gente que apueste por\u00a0personas como yo que intenta d\u00eda a d\u00eda pelear en este mundo que nos ha tocado vivir.<\/p>\n<p>La navidad empez\u00f3 malamente con ese anuncio amenazante de la Loter\u00eda Nacional, aunque si es verdad que entra dentro del lado rococ\u00f3 y estramb\u00f3tico que tienen estas fiestas. Lo pienso y es un anucio lleno de mensajes, esa cara de amenza de Montserrat Caball\u00e9 es lo que sienten muchos cuando se acerca el temido 24 de diciembre y el primer contacto con familiares que quiz\u00e1s solo ves en esta \u00e9poca del a\u00f1o, coincidir con ese primo que no soportas o ese cu\u00f1ado graciosete. Esa sonrisa final de Raphael, ese &#8220;na, na, na, na, nanana&#8221;\u00a0y esa cara \u00a0con tan pocos aditivos y colorantes como una tarta de fondant, \u00a0me recuerda a esa gente que durante el a\u00f1o se cruza de acera o hace que mira el m\u00f3vil para no saludarte hasta que te lo\u00a0encuentras en plena noche vieja con un par de copas de m\u00e1s. Muy real el anucio si se\u00f1or.<\/p>\n<p>La navidad es como una enfermedad que hay que pasar. Tienes dos opciones, poner de tu parte para que todo fluya m\u00e1s o menos bien (el alcohol ayuda una barbaridad) o estar tirado cual despojo compadeciendote de tu alma, elige lo que quieras. Te aconsejo meterte en la cocina, ponerte m\u00fasica y una copa de vino y dejarte llevar. Felices fiestas a todos.<\/p>\n<p><strong>TURR\u00d3N DE CHOCOLATE CASERO<\/strong><\/p>\n<p><a href=\"http:\/\/cocinayrecetas.hola.com\/cocinarte\/files\/2013\/12\/turr\u00f3n-de-chocolate.jpg\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/cocinayrecetas.hola.com\/cocinarte\/files\/2013\/12\/turr\u00f3n-de-chocolate.jpg\" alt=\"turr\u00f3n de chocolate\" width=\"512\" height=\"554\" \/><\/a><\/p>\n<p><strong>Ingredientes:<\/strong><\/p>\n<p><strong>125 gramos de chocolate negro del 70%<\/strong><\/p>\n<p><strong>150 gramos de chocolate con leche<\/strong><\/p>\n<p><strong>50 gramos de manteca de cerdo<\/strong><\/p>\n<p><strong>60 gramos de Chococrispis de Kellogg\u00b4s<\/strong><\/p>\n<p><strong>Una pizca de sal<\/strong><\/p>\n<p><strong>1 cucharilla peque\u00f1a<\/strong> de miel<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Proceso:<\/strong><\/p>\n<p>Trocearemos el chocolate y lo pondremos al ba\u00f1o mar\u00eda, nos ayudaremos de una esp\u00e1tula para ir removiendo, el chocolate hay que trabajarlo sin prisas y una temperatura que no sea demasiado alta. Cuando veamos que empieza a derretirse a\u00f1adiremos la manteca de cerdo, la miel y \u00a0la pizca de sal, removeremos hasta que todo est\u00e9 bien deshecho. A continuaci\u00f3n apartaremos del fuego y a\u00f1adiremos el arroz inflado, mezclaremos bien y lo echaremos en el molde. Taparemos con film transparente y dejaremos toda la noche en el frigor\u00edfico.<\/p>\n<p><em>Hay unos moldes especiales para hacer turrones, si no ten\u00e9is y usa\u00eds de otro tipo tened cuidado por si se os pega. un truco ser\u00eda cubrirlo de film transparente, lo malo es que no se os pegar\u00e1 pero no os quedar\u00e1 liso. Un truco es que espolvoree\u00eds un poco de cacao en polco por encima para que no se vean esas imperfecciones.<\/em><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Para mi las navidades son cocina, familia y amigos. Imagino que cuando a uno le gusta algo, como me pasa a mi con la cocina, quiere disfrutar de ello\u00a0y m\u00e1s cuando es para compartir con los que m\u00e1s quieres. A veces tengo mis serias dudas de que cocinar a destajo sea una satisfacci\u00f3n, las dudas [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[48,124,183],"class_list":["post-182","post","type-post","status-publish","format-standard","hentry","category-postres","tag-chocolate","tag-navidad","tag-turron"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts\/182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/comments?post=182"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts\/182\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/media?parent=182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/categories?post=182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/tags?post=182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}