{"id":245,"date":"2015-02-17T12:19:44","date_gmt":"2015-02-17T11:19:44","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sukaldatu\/?p=245"},"modified":"2015-02-17T12:19:44","modified_gmt":"2015-02-17T11:19:44","slug":"operacion-torrija-perfecta","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sukaldatu\/2015\/02\/17\/operacion-torrija-perfecta\/","title":{"rendered":"Operaci\u00f3n torrija perfecta"},"content":{"rendered":"<p>Estamos en plena \u00e9poca de torrijas y se de buena tinta que and\u00e1is prepar\u00e1ndolas por aqu\u00ed y por all\u00e1. Las torrijas es uno de esos platos f\u00e1ciles de preparar pero dif\u00edciles de hacerlos de una manera <em>high level <\/em>(de nivel\u00f3n que dir\u00edamos). Hay varios factores que hacen que este postre pase sin pena ni gloria o que haga que toquemos el cielo con los dedos de la mano. Hoy estoy dispuesta a contaros los mil y un secretos (me he pasado, no llegan a un pu\u00f1ado de trucos) para que consig\u00e1is esas torrijas a la altura de un buen restaurante de post\u00edn.<\/p>\n<p>Vamos a empezar por el ingrediente m\u00e1s importante de este delicioso postre, <strong>el pan.<\/strong>\u00a0Mi <em>deformaci\u00f3n profesional<\/em>\u00a0hace que os aleccione en este tema, trabajar el <a href=\"https:\/\/theloaf.es\/es\/\" rel=\"external nofollow\">The Loaf <\/a>\u00a0hace de mi una tiquismiquis panarra de mucho cuidado, pero en este tema concreto tengo raz\u00f3n y mucha. Ayer prepar\u00e9 torrijas con tres panes diferentes para poder documentar este post c\u00f3mo es debido. El primero de ellos con un classic (pan de masa madre con una peque\u00f1a cantidad de levadura, miga pel\u00edn gelatinosa pero no en exceso por esa aportaci\u00f3n de levadura), no quedaba una torrija bien empapada, tan solo un sut\u00edl toque para mi gusto insuficiente. La segunda prueba fu\u00e9 con pan de barra, s\u00e9 que muchos los hac\u00e9is con este tipo de pan, no me gusta esa sensaci\u00f3n tan presente de la corteza, soy de torrija con mucha miga y en este caso tampoco cumpl\u00eda mis expectativas. El tercero de los panes fu\u00e9 un delicioso pan de molde, no de molde supermercadero sin sustancia ni n\u00e1, un molde bien enriquecido con su leche y su mantequilla, su miga bien densa apta para absorber toda esa leche de la que hablaremos m\u00e1s adelante. C\u00f3mo os hab\u00e9is podido dar cuenta me quedo con esta tercera opci\u00f3n, un pan de molde de calidad y cortado en rebanadas de m\u00e1s de dos dedos de ancho (pasen por The Loaf a partir de las cuatro de la tarde y lo encontrar\u00e1n).<\/p>\n<p>Ya tenemos el pan, ahora vamos a por <strong>la leche<\/strong>. Para mi gusto tiene que ser entera, con todas sus grasas y deliciosas calor\u00edas. Debemos infusionarla con mimo por que esa va a ser la esencia, el aroma, el olor de este popular postre. Necesitaremos piel de naranja y lim\u00f3n, buena canela en rama y una vaina de vainilla (que no esencia de vainilla, no me se\u00e1is marranos). La infusinaremos a fuego lento sin que llegue a hervir y dejaremos templar antes de meter las rodajas de pan en su interior. El momento de empapar el pan tambi\u00e9n es un tema complicado, hay que empapar el pan sin que se desmorone pero tiene que estar jugoso. Os recomiendo haceros con dos espumaderas y dar la primera vuelta r\u00e1pido para que nos e os rompa, dejaremos escurrir sobre una rejilla.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/cuchara.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-247\" title=\"cuchara\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/cuchara.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/cuchara.jpg 979w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/cuchara-150x150.jpg 150w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/cuchara-300x300.jpg 300w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/cuchara-768x768.jpg 768w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Llega el momento de <strong>la fritura. <\/strong>Os recomiendo una aceite de oliva virgen extra de calidad, bueno para este y para todos los platos que pod\u00e1is preparar en vuestra cocina. La temperatura del aceite tambi\u00e9n es fundamental, caliente pero no humeante (entre 150\/160 grados). Pasaremos las torrijas con mucho cuidado por huevo batido y las freiremos. Siempre las sacaremos a \u00a0papel absorbente para quitar en exceso de aceite, incluso les pasaremos un papel por encima. Hay una opci\u00f3n de torrija sin fritura, con el pan empapado y con la terminaci\u00f3n de caramelizarla con soplete (mi preferida).<\/p>\n<p>En la recta final del tema torrijero nos encontramos con <strong>el az\u00facar. <\/strong>Aqu\u00ed tenemos varias opciones, para gustos los colores. Desde lo m\u00e1s cl\u00e1sico c\u00f3mo es rebozarlas en az\u00facar con canela o las que dan un toque m\u00e1s sofisticado y especial como es el az\u00facar caramelizado (mis preferidas). La primera opci\u00f3n es tan sencilla como pasar las torrijas una vez fritas por una mezcla de az\u00facar con un poco de canela. La segunda y mi preferida es m\u00e1s complicada porque tenemos que hacernos con un soplete de cocina ( de venta en ferreter\u00edas y grandes superficies ), echaremos az\u00facar por encima y pasaremos el soplete hasta que el az\u00facar empiece a caramelizar, tiene que quedar crujiente. El crujiente del caramelo y la melosidad de la torrija con este tipo de pan hacen para mi gusto una torrija diez.<\/p>\n<p>Ahora es el momento de p0neros los ingredientes, tambi\u00e9n os dejo el enlace a mi otro blog para que ve\u00e1is con m\u00e1s detenimiento las diferentes torrijas que pod\u00e9is preparar. <em>Pan para torrijas, torrijas tradicionales y mi receta favorita<a href=\"http:\/\/unrincondemicocina.com\/2013\/04\/01\/pan-para-torrijas-torrijas-tradicionales-y-mi-receta-favorita\/\" rel=\"external nofollow\"> (enlace)<\/a>. \u00a0<\/em>Las torrijas se pueden acompa\u00f1ar de helado, frutos rojos, una crema de yogurt&#8230; No las dej\u00e9is solas, bien acompa\u00f1adas hacen de ellas un grandioso postre.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/torrija.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-246\" title=\"torrija\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/torrija.jpg\" alt=\"\" width=\"979\" height=\"979\" srcset=\"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/torrija.jpg 979w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/torrija-150x150.jpg 150w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/torrija-300x300.jpg 300w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/torrija-768x768.jpg 768w\" sizes=\"auto, (max-width: 979px) 100vw, 979px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>Ingredientes.<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>1\/2 litro de leche<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>1 rama de canela<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>1\/2 vaina de vainilla<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>3 cucharas soperas de az\u00facar<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>La piel de medio lim\u00f3n<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>La piel de media naranja<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Huevo<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Aceite de oliva<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Az\u00facar y canela<\/strong><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/frontal.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-248\" title=\"frontal\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/frontal.jpg\" alt=\"\" width=\"300\" height=\"224\" srcset=\"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/frontal.jpg 979w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/frontal-300x225.jpg 300w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/02\/frontal-768x576.jpg 768w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">On egin!<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Estamos en plena \u00e9poca de torrijas y se de buena tinta que and\u00e1is prepar\u00e1ndolas por aqu\u00ed y por all\u00e1. Las torrijas es uno de esos platos f\u00e1ciles de preparar pero dif\u00edciles de hacerlos de una manera high level (de nivel\u00f3n que dir\u00edamos). Hay varios factores que hacen que este postre pase sin pena ni gloria [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,13,15],"tags":[32,42,116,129,139,140,173,179],"class_list":["post-245","post","type-post","status-publish","format-standard","hentry","category-panes","category-postres","category-recetas-de-cocina","tag-azucar","tag-caramelo","tag-leche","tag-pan","tag-popular","tag-postre","tag-the-loaf","tag-torrijas"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts\/245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/comments?post=245"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts\/245\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/media?parent=245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/categories?post=245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/tags?post=245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}