{"id":250,"date":"2015-04-28T10:13:26","date_gmt":"2015-04-28T09:13:26","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sukaldatu\/?p=250"},"modified":"2015-04-28T10:13:26","modified_gmt":"2015-04-28T09:13:26","slug":"que-comen-nuestros-hijos-en-el-colegio","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sukaldatu\/2015\/04\/28\/que-comen-nuestros-hijos-en-el-colegio\/","title":{"rendered":"\u00bfQu\u00e9 comen nuestros hijos en el colegio?"},"content":{"rendered":"<p>Llevaba tiempo queriendo saber qu\u00e9 come mi hija en el cole. Tan importante es qu\u00e9 ha aprendido nuevo cada d\u00eda como saber qu\u00e9 ha comido y si le ha gustado. Mi peque\u00f1a Laia esta hecha una peque\u00f1a <em>Chicote<\/em>\u00a0(d\u00edcese de aquel con el morro fino y la lengua afilada) y se de buena tinta que esta hecha una sacafallos. A punto he estado en mas de una ocasi\u00f3n de preguntar en secretar\u00eda si cab\u00eda la posibilidad de comer un d\u00eda con ellos, tan s\u00f3lo por salir de dudas de si esos casi seis euros que pagamos a diario son dignos de nuestros peque\u00f1os comensales. Leo el men\u00fa y he de reconocer que hay platos que me ponen los pelos como escarpias y que aunque en un ejercicio de autoconvencimiento intento pensar que todo esto esta pensado, examinado y bien ejecutado hay una parte de mi que sabe que una pizza o un pescado cocinado cinco o seis horas antes de comerlo no puede estar bueno.<\/p>\n<p>Nos preocupamos de c\u00f3mo van en mates o si aprenden a leer correctamente pero no nos paramos mucho a pensar qu\u00e9 comen y de que manera. Nos cuentan que estos men\u00fas est\u00e1n analizados por nutricionistas y profesionales del sector alimentario (no lo quiero poner en duda), me asaltan mil dudas cu\u00e1ndo leo nombres de pescados como <em>Tilapia <\/em>o <em>Granadero. <\/em>Est\u00e1 claro que con toda probabilidad no sep\u00e1is qu\u00e9 clase de pescados son estos, de hecho suele ser una pregunta habitual de padres y madres a las cinco en el patio del cole. De verdad, de coraz\u00f3n (de este coraz\u00f3n de peque\u00f1a cocinera que sufre por estos peque\u00f1os) no creo que ninguno de ustedes vayan al mercado a adquirir ninguno de estos espec\u00edmenes, ni tan siquiera los imagino en un restaurante eligi\u00e9ndolos para su men\u00fa diario. Pero no echamos cuenta de que ellos, esos peque\u00f1os pedacitos de nuestro ser coman esos productos que desconocemos, nos conformamos con pensar que ser\u00e1 bueno para ellos. Ni un pescado tra\u00eddo de \u00c1frica ni uno que su m\u00e1xime ser\u00eda dar sabor a un fum\u00e9 son dignos de un men\u00fa que nos cuesta unas cuantas docenas de euros al mes. No encuentro ese equilibrio necesario de pescado azul, blanco, carnes rojas y blancas. Ser\u00eda maravilloso que verduras y primeros platos fueran tratados con cari\u00f1o y mimo en las cocinas de los centros educativos. Ser\u00eda maravilloso que la comunidad educativa se tomara en serio el tema de la alimentaci\u00f3n porque al fin y al cabo es parte de su formaci\u00f3n y crecimiento. Este tema preocupa, sobre todo para padres y madres que como yo no les queda otro remedio de dejarlos y confiar en que comer\u00e1n correctamente.<\/p>\n<p><strong>Askora <\/strong>en un ejercicio de transparencia elabor\u00f3 una campa\u00f1a para que todo esto no fuera un misterio y tuvi\u00e9ramos que confiar en ellos como si de un algo divino se tratara. <em>Etxean By Askora<\/em>\u00a0es una campa\u00f1a de publicidad o un tanteo de un mercado abierto que son las casas d\u00f3nde no se cocina. Cog\u00ed el folleto con la desconfianza de la calidad de una Tilapia y mal pensando que era muy probable que la comida que llegar\u00eda a mi casa no se parecer\u00eda a lo que come mi peque\u00f1a.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/askora.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-251\" title=\"askora\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/askora.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/askora.jpg 979w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/askora-150x150.jpg 150w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/askora-300x300.jpg 300w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/askora-768x768.jpg 768w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Ten\u00edamos la opci\u00f3n de cuatro men\u00fas, nuestra elecci\u00f3n fu\u00e9 el men\u00fa &#8220;Julen&#8221;. Crema de calabac\u00edn local y ecol\u00f3gica con patata alavesa, hamburguesa con salsa de tomate casero y ecol\u00f3gico y yogurt local. Dif\u00edcil enga\u00f1arnos en mi casa. Me cost\u00f3 que mi peque fuera capaz de probar la comida porque lo que hab\u00eda despertado su inter\u00e9s se esfum\u00f3 al oir: &#8220;comida del comedor en casa&#8221;, sali\u00f3 despavorida como si un calambre recorriera su cuerpo al grito de &#8220;noooooooo&#8221;. Consegu\u00ed convencerla y mi peque\u00f1a \u00a0Chicote me argument\u00f3 porque esa comida no era como la del comedor con frases como: &#8220;las hamburguesas del comedor no traen esa salsa, es mas naranja. El pur\u00e9 no es tan claro y no sabe as\u00ed y el yogurt del comedor no es tan rico&#8221;. Mi traducci\u00f3n es: &#8220;hemos cocinado mejor para que creas que tus hijos comen bien&#8221;, lo que me hace llegar a la conclusi\u00f3n de que quiz\u00e1s coman peor de lo que pensamos. El pur\u00e9 estaba sospechosamente engordado con alguna f\u00e9cula o patata deshidratada, harina de ma\u00edz o similar. La hamburguesa ten\u00eda una salsa de tomate mas que digna que me qued\u00f3 muy claro que NO es la que les \u00a0ponen el el colegio y el yogurt, \u00a1ay el yogurt! sin marca comercial, apuesto que de marca Goenaga no es el Danone que les dan a nuestros hijos.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/men\u00fa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-252\" title=\"men\u00fa\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/men\u00fa.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/men\u00fa.jpg 979w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/men\u00fa-150x150.jpg 150w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/men\u00fa-300x300.jpg 300w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/men\u00fa-768x768.jpg 768w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/men\u00fa.jpg\"><br \/>\n<\/a><\/p>\n<p>Hubiera estado bien. Hubiera estado pero que muy bien ese ejercicio de transparencia de verdad. Me gustar\u00eda que se cocinara en los colegios, pagar\u00eda por ello. Al igual de interesarnos por el proyecto educativo de un centro tambi\u00e9n nos tendr\u00edamos que preocupar c\u00f3mo se alimentan nuestros hijos en el cole. Deber\u00eda importarnos, deber\u00edamos plantearnos que ese dinero que pagamos mensualmente podr\u00eda tener mejor destino. Esto no tiene nada que ver con una empresa o la otra, desde Askora hasta Auzolan me parece que las cosas se podr\u00edan hacer mejor y como padres est\u00e1 en nuestra mano hacer lo posible para cambiar las cosas.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/yogurt.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-253\" title=\"yogurt\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/yogurt.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/yogurt.jpg 979w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/yogurt-150x150.jpg 150w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/yogurt-300x300.jpg 300w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/04\/yogurt-768x768.jpg 768w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/p>\n<p>Un ni\u00f1o bien alimentado ser\u00e1 un ni\u00f1o sano y feliz. Un adulto que se preocupa por la alimentaci\u00f3n de sus hijos es una persona responsable con el futuro de sus peque\u00f1os.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Llevaba tiempo queriendo saber qu\u00e9 come mi hija en el cole. Tan importante es qu\u00e9 ha aprendido nuevo cada d\u00eda como saber qu\u00e9 ha comido y si le ha gustado. Mi peque\u00f1a Laia esta hecha una peque\u00f1a Chicote\u00a0(d\u00edcese de aquel con el morro fino y la lengua afilada) y se de buena tinta que esta [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5,7],"tags":[23,31,54,55,125],"class_list":["post-250","post","type-post","status-publish","format-standard","hentry","category-gastronomia","category-historias","category-hosteleria-y-ninos","tag-alimentacion","tag-askora","tag-colegio","tag-comedor","tag-ninos"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts\/250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/comments?post=250"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts\/250\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/media?parent=250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/categories?post=250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/tags?post=250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}