{"id":26,"date":"2012-10-09T21:35:30","date_gmt":"2012-10-09T20:35:30","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sukaldatu\/?p=22"},"modified":"2012-10-09T21:35:30","modified_gmt":"2012-10-09T20:35:30","slug":"san-sebastian-gastronomika-olor-y-sabor","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sukaldatu\/2012\/10\/09\/san-sebastian-gastronomika-olor-y-sabor\/","title":{"rendered":"San Sebastian Gastronomika. Olor y sabor."},"content":{"rendered":"<p style=\"text-align: left;\">Mi dia ha empezado con una ponencia de Los Bistrots de la mano de I\u00f1aki Azpitarte.\u00a0 Ha sido una magn\u00edfica ma\u00f1ana, muy intensa y cruel. Cruel por el maravilloso olor que invad\u00eda la sala de congresos del Kursaal.\u00a0\u00a0 De esta ponencia destacaria la sencillez con la que viven la gastronomia a nivel de Bistrot, lo tratan como un algo autentico. Los Bistrots son la recomendaci\u00f3n que nos dan si queremos saborear esa gastronom\u00eda aut\u00e9ntica. El chef nos ha deleitado con un curioso plato de bacalao e hinojo, con unas texturas de gelatina y crujiente de hinojo tan f\u00e1ciles de preparar como interesantes. La verdad es que esta ponencia ha sido tan cercana como el video familiar que ha utilizado el chef para introducirnos en su receta de tocino de cielo, basada en sus viajes al sur de nuestro\u00a0pa\u00eds.<\/p>\n<p style=\"text-align: left;\">La ma\u00f1ana ha continuado con la cocina Alpina de Jean Sulpice del Restaurante L\u00b4Oxalys (Val. Thorens). En este caso me ha sorprendido la cocina Alpina, no hubiera imaginado las dificultades a\u00f1adidas que tiene cocinar a 2000 metros de altura sobre el nivel del mar. Segun su chef probablemente el restaurante con mas altitud del mundo. Para que os hagais una idea cambia hasta el punto de ebullicion del agua, de 100 grados a 80 y asi basandose toda su cocina en una aventura\u00a0gastron\u00f3mica\u00a0en la que\u00a0dos mas dos no son cuatro. Ya no solo la altitud condiciona las temperaturas sino tambien el grado de humedad, obligandoles a cocinar las carnes en cazuelas especiales. Tiene un gran respeto por el entorno y por la materia prima. Entendiendo el ecosistema\u00a0 que le rodea. Haciendo de la vegetaci\u00f3n y la fauna que vive en su zona parte de su arte culinario.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2012\/10\/ponencias.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24\" title=\"ponencias\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2012\/10\/ponencias.jpg\" alt=\"\" width=\"300\" height=\"170\" \/><\/a><\/p>\n<p style=\"text-align: left;\">La ma\u00f1ana ha continuado con el chef Jean Luis Nomicos. En esta ocasi\u00f3n nos ha transmitido el mimo con el producto. Asi como darnos ideas de c\u00f3mo un mismo plato puede tener varias versiones. Su ponencia ha sido un poco ca\u00f3tica pero el resultado variado y lleno de matices.<\/p>\n<p style=\"text-align: left;\">Los tres ponentes de la ma\u00f1ana han coincidido en varios de los productos, no tanto asi como en las recetas. La remolacha y el hinojo han estado presentes en casi todas las ponencias de esta ma\u00f1ana de martes.<\/p>\n<p style=\"text-align: left;\">Una servidora ten\u00eda ganas de escuchar a Phippe Mille con Los secretos de Foie. La t\u00e9cnica de cocina al vac\u00edo ha sido su secreto mejor guardado. Un foie dorado ligeramente y cocinado al vac\u00edo con jugo de remolacha. Desde luego la textura parecia melosa y no se desperdicia pr\u00e1cticamente nada del producto.<\/p>\n<p style=\"text-align: left;\">Hoy lo he disfrutado. He aprendido, escuchado y hablado con mucha gente. La zona VIP del congreso hace del mediodia una break donde descansar, comer y sobre todo charlar. El paseo gastron\u00f3mico por Francia esta siendo una delicia. \u00bfQu\u00e9 sabrosas experiencias nos deparar\u00e1 el \u00faltimo d\u00eda de congreso? Eso os lo cuento otro dia.<\/p>\n<p><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2012\/10\/final.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25\" title=\"final\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2012\/10\/final.jpg\" alt=\"\" width=\"300\" height=\"300\" \/><\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Mi dia ha empezado con una ponencia de Los Bistrots de la mano de I\u00f1aki Azpitarte.\u00a0 Ha sido una magn\u00edfica ma\u00f1ana, muy intensa y cruel. Cruel por el maravilloso olor que invad\u00eda la sala de congresos del Kursaal.\u00a0\u00a0 De esta ponencia destacaria la sencillez con la que viven la gastronomia a nivel de Bistrot, lo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-26","post","type-post","status-publish","format-standard","hentry","category-lugares"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts\/26\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/media?parent=26"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/categories?post=26"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/tags?post=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}