{"id":282,"date":"2015-10-07T14:59:17","date_gmt":"2015-10-07T13:59:17","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sukaldatu\/?p=282"},"modified":"2015-10-07T14:59:17","modified_gmt":"2015-10-07T13:59:17","slug":"esta-donostia-preparada-para-la-cocina-internacional","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sukaldatu\/2015\/10\/07\/esta-donostia-preparada-para-la-cocina-internacional\/","title":{"rendered":"\u00bfEst\u00e1 Donostia preparada para la cocina internacional?"},"content":{"rendered":"<p>Nos gusta la cocina, la mesa y el buen comer en \u00e9sta ciudad, no me cabe la menor duda. Adem\u00e1s somos comensales exigentes y estamos puestos en lo \u00faltimo, en clasic\u00edsmo y vanguardia. Nos hacemos los expertos, incluso nos gusta alardear de los productos que somos capaces de conseguir. La autenticidad de lo que comemos, d\u00f3nde compramos e incluiso c\u00f3mo lo cocinamos. Nos gusta ser una tierra d\u00f3nde el disfrute de la cocina incluso se interioriza mucho antes que en otros muchos sitios. La gastronom\u00eda ha llegado hasta hacerse un hueco en el Festival Internacional de Cine de San Sebasti\u00e1n, por no decir que el congreso Gastronomika es con toda probabilidad el mejor en el panorama internacional. Recuerdo siendo adolescente como nos ret\u00e1bamos en la *cuadrilla (*d\u00edcese de ese grupo de personas que comparten amistad, vaso de cerveza, charla, f\u00fatbol o lo que haga falta pero siempre con ese toque a familia, a familia de la que se escoge) cada vez que hac\u00edamos una cena, no val\u00eda cualquier cosa comprada en el supermercado. Cu\u00e1ndo en nuestra mesa se sentaban invitados venidos de otros lugares no daban cr\u00e9dito que no sucumbi\u00e9ramos a pizzas y dem\u00e1s alimentos m\u00e1s habituales en esas edades. Gracias a esto hemos ganado en charlas al calor de los fogones, intercambio de recetas y he de confesar que gracias a estas cenas y a estos platos compartidos una servidora termin\u00f3 siendo bloggera.<\/p>\n<p>T\u00e1nto nos gusta la cocina y los buenos manjares que hay algo que siempre ronda mi cabeza. He estado estos d\u00edas de congreso intentado recordar cu\u00e1ntos restaurantes de cocina internacional ha podido haber en Donostia las \u00faltimas dos d\u00e9cadas, San Google no tiene mucha idea y de lo poco que he conseguido recordar\u00a0 e incluso preguntar a ciudadanos de buen comer que me he encontrado estos d\u00edas por el Kursaal la informaci\u00f3n es m\u00ednima. Recuerdo siendo bien peque\u00f1a un hind\u00fa situado cerca de la plaza Easo, lo recuerdo como un liban\u00e9s que tan solo dur\u00f3 unos meses, un mejicano en la parte Vieja donostiarra, un alem\u00e1n situado en el barrio de Gros, un argentino en el centro y as\u00ed hasta unos cuantos locales de restauraci\u00f3n de cocina internacional que no han tenido un hueco en esta ciudad que disfruta casi como ninguna de su gastronom\u00eda. Me hace pensar que quiz\u00e1s nos gusta <em>nuestra<\/em> gastronom\u00eda, que quiz\u00e1s para lo dem\u00e1s tan s\u00f3lo le damos la m\u00ednima oportunidad y esa m\u00ednima oportunidad se reduce a ir una o dos veces a un local d\u00f3nde no te sirvan comida tradicional de aqui.<\/p>\n<div id=\"attachment_285\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/10\/IMG_5860.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-285\" class=\"size-medium wp-image-285\" title=\"IMG_5860\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/10\/IMG_5860.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/10\/IMG_5860.jpg 2448w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/10\/IMG_5860-150x150.jpg 150w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/10\/IMG_5860-300x300.jpg 300w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/10\/IMG_5860-768x768.jpg 768w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/10\/IMG_5860-1024x1024.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-285\" class=\"wp-caption-text\">Choribao de Estanis Carenzo<\/p><\/div>\n<p>No pasamos del chino de toda la vida o japon\u00e9s,que si que tengo que dar la raz\u00f3n a los que ahora estar\u00e9is pensando que con la moda del sushi, ram\u00e9n y dem\u00e1s manjares asi\u00e1ticos unos pocos se han hecho hueco entre los locales de la ciudad, y del italiano que su mayor riesgo es echar r\u00facula a la pizza una vez horneada. Este tema no se queda s\u00f3lo en el tema de los restaurantes, se hace casi imposible acceder a ciertos ingredientes que facilmente se pueden encontrar en otras ciudades. No hace falta que busques nada complicado, con que quiereas unas flores de calbac\u00edn en Donostia est\u00e1s fastidiado.<\/p>\n<div id=\"attachment_286\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/10\/IMG_5862.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-286\" class=\"size-medium wp-image-286\" title=\"IMG_5862\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/10\/IMG_5862.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/10\/IMG_5862.jpg 2448w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/10\/IMG_5862-150x150.jpg 150w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/10\/IMG_5862-300x300.jpg 300w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/10\/IMG_5862-768x768.jpg 768w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2015\/10\/IMG_5862-1024x1024.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-286\" class=\"wp-caption-text\">Rap\u00e1n de Vladimir Mukhin<\/p><\/div>\n<p>No es que me de pena porque lo que el cliente pone o quita es totalmente l\u00edcito, por eso soporto ese horrible Mc. Donalds en pleno Boulevard. Este \u00faltimo lo podr\u00edamos considerar cocina internacional porque <em>adi\u00f3sgracias <\/em>su &#8220;comida&#8221; no tiene mucho que ver con nuestra tierra.<\/p>\n<p>Me parece curioso que tan abiertos que somos para poder sostener tanto local de restauraci\u00f3n con o sin estrellas de esas tan famosas siendo arriesgados y capaces de fusionar cocinas de diferentes paises no seamos capaces de soportar un restaurante ruso, ind\u00fa, alem\u00e1n o de d\u00f3nde sea que quieran venir.<\/p>\n<p>Cada vez que me ponen un <em>choribao <\/em>como el de Estanis Carenzo (argentino), un <em>rap\u00e1n <\/em>de Vladimir Mukhin (Rusia), cada vez que siento la fortuna de poder degustar platos de otros paises me asalta la pregunta, \u00bfest\u00e1 Donostia preparada para la cocina internacional?<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Nos gusta la cocina, la mesa y el buen comer en \u00e9sta ciudad, no me cabe la menor duda. Adem\u00e1s somos comensales exigentes y estamos puestos en lo \u00faltimo, en clasic\u00edsmo y vanguardia. Nos hacemos los expertos, incluso nos gusta alardear de los productos que somos capaces de conseguir. La autenticidad de lo que comemos, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,6,9,17],"tags":[51,58,128,152],"class_list":["post-282","post","type-post","status-publish","format-standard","hentry","category-historias","category-hosteleria-donostiarra","category-lugares","category-san-sebastian-gastronomika","tag-cocina-internacional","tag-comida","tag-paises","tag-restaurantes"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts\/282\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/media?parent=282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/categories?post=282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/tags?post=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}