{"id":330,"date":"2016-06-02T13:25:54","date_gmt":"2016-06-02T12:25:54","guid":{"rendered":"http:\/\/blogs.diariovasco.com\/sukaldatu\/?p=330"},"modified":"2016-06-02T13:25:54","modified_gmt":"2016-06-02T12:25:54","slug":"keler-pintxo-week-que-no-se-diga-que-no-se-puede-ir-de-pintxos","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/sukaldatu\/2016\/06\/02\/keler-pintxo-week-que-no-se-diga-que-no-se-puede-ir-de-pintxos\/","title":{"rendered":"Keler Pintxo Week. Que no se diga que  no se puede ir de pintxos."},"content":{"rendered":"<p>Ya se que es o\u00edr: &#8220;pintxos en Donostia&#8221; y todos o muchos caen en lo mismo -qu\u00e9 caros son los pintxos en tu ciudad-. Lo he o\u00eddo muchas veces y este es un tema en el que otro d\u00eda profundizar\u00e9 con mucho gusto y hablaremos de lo que deber\u00eda o no deber\u00eda ser un pintxo, de la honestidad de muchos hosteleros y la falta de sentido com\u00fan de otros. La verdad es que es un tema peliagudo y desde el verano pasado navegan por la red docenas de tickets de indignados por sentirse atracados a mano armada (en muchos caso no me sorprende).<\/p>\n<div id=\"attachment_335\" style=\"width: 330px\" class=\"wp-caption aligncenter\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-7.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-335\" class=\"size-full wp-image-331  \" title=\"FullSizeRender (7)\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-7.jpg\" alt=\"\" width=\"320\" height=\"320\" srcset=\"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-7.jpg 320w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-7-150x150.jpg 150w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-7-300x300.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><\/dt>\n<\/dl>\n<\/div>\n<p>Hoy os traigo buenas noticias, se puede ir de pintxos y de cervecitas con la tranquilidad de saber que a 10\u20ac se le puede sacar un partido impresionante, m\u00e1s de lo que te puedas imaginar. De la mano de Keler podemos disfrutar del 3 al 12 de junio y con la participaci\u00f3n de mas de 30 locales donostiarras, de cuatro pintxos y dos cervezas Keler de 33cl.<\/p>\n<div class=\"mceTemp mceIEcenter\">\n<dl id=\"attachment_335\" class=\"wp-caption aligncenter\" style=\"width: 330px;\">\n<dt class=\"wp-caption-dt\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-6.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-335\" class=\"size-full wp-image-335\" title=\"FullSizeRender (6)\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-6.jpg\" alt=\"\" width=\"320\" height=\"320\" srcset=\"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-6.jpg 320w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-6-150x150.jpg 150w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-6-300x300.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><p id=\"caption-attachment-335\" class=\"wp-caption-text\">Ensaladilla del Bar Ezkurra<\/p><\/div>\n<p>No est\u00e1 mal la oferta, adem\u00e1s esta 5\u00aa edici\u00f3n y el conocimiento de c\u00f3mo han funcionado las anteriores, hacen que la confianza en el buen hacer de los hosteleros est\u00e1 asegurado. No queda ah\u00ed la cosa, adem\u00e1s de poder alegrar est\u00f3mago y mente podemos juzgar y poner en valor nuestra opini\u00f3n votando a los mejores pintxos. El jurado seremos nosotros y este voto har\u00e1 que formemos parte de un sorteo para una cena en Arzak.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-332\" title=\"FullSizeRender (4)\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-4.jpg\" alt=\"\" width=\"320\" height=\"320\" srcset=\"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-4.jpg 320w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-4-150x150.jpg 150w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-4-300x300.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><\/p>\n<p>Si todo lo que os he contado no es suficiente para que est\u00e9is deseando ir a tomar una Keler fresquita con unos buenos pintxos meteros en en \u00a0la p\u00e1gina de Facebook de Gastronosfera y haceros a la idea de todo lo que pod\u00e9is disfrutar.<\/p>\n<div id=\"attachment_336\" style=\"width: 330px\" class=\"wp-caption aligncenter\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-336\" class=\"size-full wp-image-336\" title=\"FullSizeRender (1)\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-1.jpg\" alt=\"\" width=\"320\" height=\"320\" srcset=\"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-1.jpg 320w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-1-150x150.jpg 150w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-1-300x300.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><p id=\"caption-attachment-336\" class=\"wp-caption-text\">Ostras de Kata4<\/p><\/div>\n<p>Esta gente de Keler y muchos hosteleros donostiarras marcan casi el inicio del verano y el fin de la operaci\u00f3n bikini, porque se\u00f1oras y se\u00f1ores no creo que una lechuga pueda poner la misma sonrisa en tu boca como lo puede hacer una cerveza fresca, buena comida y sobre todo buena compa\u00f1\u00eda, esto \u00faltimo lo tienes que poner t\u00fa. No debe ser mala cosa cuando en anteriores ediciones unas 12000 personas han participado de una de las cosas que mejor sabemos hacer los vascos, comer, beber y disfrutar.<\/p>\n<div id=\"attachment_333\" style=\"width: 330px\" class=\"wp-caption aligncenter\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-3.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-333\" class=\"size-full wp-image-333\" title=\"FullSizeRender (3)\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-3.jpg\" alt=\"\" width=\"320\" height=\"320\" srcset=\"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-3.jpg 320w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-3-150x150.jpg 150w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-3-300x300.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><p id=\"caption-attachment-333\" class=\"wp-caption-text\">Pulpo del Mes\u00f3n Martin<\/p><\/div>\n<p>Coged el cat\u00e1logo y organizaros una ruta, o varias que hay mucho para probar y para disfrutar. Delimitado en tres zonas como el <strong>Centro<\/strong> (San Marcial, Bar rojo y negro, Iombi, Kata 4, Boulevard y mes\u00f3n Mart\u00edn),<strong> Gros<\/strong> (Zinema korner, Vinorelas Wine shop, la piazzeta, ama-lur, bodega donostiarra, caf\u00e9 kursaal, ramuntxo berri, Tom\u00e1s Gros, ViuraII, Txartela, Motoclub, Gaztelutxiki, restaurante Khaki Campbell, the Caledonian, Senra, Ezkurra y Bar Oscar) y <strong>Parte Vieja<\/strong> (Ambig\u00fa, Sport, Bokado San Telmo, Txuleta, Txoko, Etxaniz y Dakara bi), la oferta es variada y muy atractiva.<\/p>\n<div id=\"attachment_334\" style=\"width: 330px\" class=\"wp-caption aligncenter\"><a href=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-5.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-334\" class=\"size-full wp-image-334\" title=\"FullSizeRender (5)\" src=\"\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-5.jpg\" alt=\"\" width=\"320\" height=\"320\" srcset=\"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-5.jpg 320w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-5-150x150.jpg 150w, https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-content\/uploads\/sites\/39\/2016\/06\/FullSizeRender-5-300x300.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><p id=\"caption-attachment-334\" class=\"wp-caption-text\">Vinagres de la Bodega Donostiarra<\/p><\/div>\n<p>As\u00ed de interesante empieza el mes de junio para ir abriendo boca y ponernos nerviosos por la proximidad de la \u00e9poca estival. Se me olvidaba, para los frikis (no se sientan ofendidos que yo soy una de ellas)que les guste sacar fotos de lo que comen y compartirlo en redes sociales tambi\u00e9n tendr\u00e1n premio. Beban coman y disfruten que la vida pesa demasiado como para no quitarse la mochila de vez en cuando.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ya se que es o\u00edr: &#8220;pintxos en Donostia&#8221; y todos o muchos caen en lo mismo -qu\u00e9 caros son los pintxos en tu ciudad-. Lo he o\u00eddo muchas veces y este es un tema en el que otro d\u00eda profundizar\u00e9 con mucho gusto y hablaremos de lo que deber\u00eda o no deber\u00eda ser un pintxo, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6,9],"tags":[70,104,114,115,135],"class_list":["post-330","post","type-post","status-publish","format-standard","hentry","category-gastronomia","category-hosteleria-donostiarra","category-lugares","tag-donostia","tag-hosteleria","tag-keler","tag-kelerpintxoweek","tag-pintxos"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts\/330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/comments?post=330"}],"version-history":[{"count":0,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/posts\/330\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/media?parent=330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/categories?post=330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/sukaldatu\/wp-json\/wp\/v2\/tags?post=330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}