{"id":1731,"date":"2021-03-10T07:00:51","date_gmt":"2021-03-10T06:00:51","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/?p=1731"},"modified":"2021-03-08T18:06:48","modified_gmt":"2021-03-08T17:06:48","slug":"comer-en-compania","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/2021\/03\/10\/comer-en-compania\/","title":{"rendered":"Comer en compa\u00f1\u00eda"},"content":{"rendered":"<p>El diccionario nos indica que comer significa <em>\u201ctomar alimento por la boca, en especial un alimento s\u00f3lido, mastic\u00e1ndolo y trag\u00e1ndolo para que pase al est\u00f3mago y alimentarnos\u201d.<\/em> Pero cuando realizamos el acto de comer en compa\u00f1\u00eda, en realidad, lo que verdaderamente estamos <strong>alimentando<\/strong> es nuestra alma con la colaboraci\u00f3n de quienes nos rodean. Por supuesto, hay muchos tipos de comidas en compa\u00f1\u00eda diferentes, pueden ser de trabajo, familiares, con amigos, rom\u00e1nticas\u2026 \u00a0Compartir una comida con otras personas puede significar un disfrute mucho mayor que el mero hecho de ingerir alimentos.<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1732\" src=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/comida3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/comida3-300x200.jpg 300w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/comida3-768x512.jpg 768w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/comida3-628x419.jpg 628w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/comida3.jpg 1050w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Por este motivo, es importante cumplir unas normas para que la comida sea lo m\u00e1s agradable posible para todos y se pueda <strong>disfrutar<\/strong> al m\u00e1ximo de los beneficios de comer juntos:<\/p>\n<ul>\n<li>Mantener buenos modales en la mesa. Aunque pueda parecer una obviedad, si nos fijamos bien no es tan sencillo hoy en d\u00eda que todos los comensales sepan actuar con educaci\u00f3n en la mesa.<\/li>\n<li>Participar en la conversaci\u00f3n, tomando parte de la misma y mostrando nuestro inter\u00e9s por escuchar las opiniones de los dem\u00e1s, a parte de compartir la nuestra.<\/li>\n<li>Tener claro que no pasa nada por discutir, si se hace con respeto, establecer un debate ayuda a entendernos mejor y conocer a las personas que nos rodean.<\/li>\n<li>No levantarnos de la mesa antes de tiempo, ya que no s\u00f3lo se interrumpe la conversaci\u00f3n, sino que se puede poner nervioso a quien a\u00fan est\u00e1 comiendo, algo muy molesto para quienes se quedan en la mesa.<\/li>\n<li>Colaborar en colocar, llevar y recoger la mesa. A no ser que la comida se desarrolle en un restaurante o en un sitio en donde haya servicio de mesa, es importante que todos los comensales se involucren en el trabajo de servir, a no ser que el anfitri\u00f3n pida expresamente lo contrario, para igualarnos y que estos momentos tambi\u00e9n sean compartidos.<\/li>\n<li>Como he comentado anteriormente se puede debatir sin ofender a los dem\u00e1s, por esto, a veces es mejor evitar ciertos temas que sabemos pueden tensionar la conversaci\u00f3n de forma desagradable.<\/li>\n<li>Disfrutar tanto de la comida como de la compa\u00f1\u00eda, saboreando cada momento y degustando cada sabor.<img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-1733\" src=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/comida4-240x300.jpg\" alt=\"\" width=\"240\" height=\"300\" srcset=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/comida4-240x300.jpg 240w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/comida4-503x628.jpg 503w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/comida4.jpg 701w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/li>\n<\/ul>\n<p>Puede ser que teniendo en cuenta la situaci\u00f3n en la que nos encontramos nos cueste m\u00e1s poder disfrutar de estos momentos, pero por otra parte, tambi\u00e9n es verdad que nos est\u00e1 ayudando a <strong>valorar<\/strong> m\u00e1s las comidas en compa\u00f1\u00eda. Espero que pronto podamos hacerlo sin tener que contar el n\u00famero de personas que nos sentamos en la mesa, y podamos volver a sentirnos bien por disfrutar de nuestros seres queridos.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El diccionario nos indica que comer significa \u201ctomar alimento por la boca, en especial un alimento s\u00f3lido, mastic\u00e1ndolo y trag\u00e1ndolo para que pase al est\u00f3mago y alimentarnos\u201d. Pero cuando realizamos el acto de comer en compa\u00f1\u00eda, en realidad, lo que verdaderamente estamos alimentando es nuestra alma con la colaboraci\u00f3n de quienes nos rodean. Por supuesto, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1731","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/comments?post=1731"}],"version-history":[{"count":1,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1731\/revisions"}],"predecessor-version":[{"id":1734,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1731\/revisions\/1734"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/media?parent=1731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/categories?post=1731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/tags?post=1731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}