{"id":1736,"date":"2021-03-17T07:00:37","date_gmt":"2021-03-17T06:00:37","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/?p=1736"},"modified":"2021-03-16T20:45:52","modified_gmt":"2021-03-16T19:45:52","slug":"la-importancia-de-escoger-bien-tus-palabras","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/2021\/03\/17\/la-importancia-de-escoger-bien-tus-palabras\/","title":{"rendered":"La importancia de escoger bien tus palabras"},"content":{"rendered":"<p>Muchas veces he comentado en este blog la importancia de escoger bien las palabras para poder transmitir el mensaje adecuado, y hace unos d\u00edas un amigo me env\u00edo la siguiente tabla que me ha parecido interesante para poder resumir en ciertas frases hechas este asunto. Parto de la base de que utilizar <strong>la asertividad<\/strong> es la forma m\u00e1s directa a la vez que correcta y respetuosa de comunicarnos, y como este es un tema del que surgen muchos problemas, creo que esta tabla puede servirnos de ayuda para lograr nuestros prop\u00f3sitos sin crearnos ning\u00fan conflicto.<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1737\" src=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/palabras-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/palabras-300x225.jpg 300w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/palabras.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Aunque considero que estas frases nos pueden servir de ayuda, debo decir que discrepo con algunas de las frases marcadas como correctas, como, por ejemplo, cuando quieres comprobar si te han entendido no hay que preguntar si te est\u00e1s explicando bien. Es muy habitual en estos casos preguntar si entiendes, lo que es totalmente incorrecto, ya que est\u00e1s insinuando que es la otra persona quien no es capaz de entender, en lugar de ser t\u00fa quien no eres capaz de explicarte bien. Por este motivo, no creo que es peor preguntar si me estoy explicando bien a animarte a preguntar si te surge alguna duda. De todos modos, debemos tener en cuenta que las palabras s\u00f3lo representan el 7% del mensaje que enviamos, por lo tanto, cambia mucho el significado dependiendo el tono, volumen o nuestra expresi\u00f3n facial a la hora de comunicarnos.<\/p>\n<p>Otra de las frases que creo que se puede mejorar en esta tabla es la referente a contestar cuando te dan las gracias. Tendemos a dejarnos llevar por la \u201cfalsa modestia\u201d y quitar importancia a lo que hacemos por los dem\u00e1s. Por supuesto, sabemos que ayudar nos proporciona mayor placer que ser ayudados. Pero, esto no quiere decir que debamos restar importancia a nuestros actos, y no dejar que nos agradezcan por ellos. Si alguien considera que debe agradecer nuestra participaci\u00f3n en un asunto que le haya servido de utilidad, podemos aceptar ese agradecimiento de forma natural y sin excusarnos por ello. Por este motivo, y en deferencia a quien nos da las gracias podemos aceptarlas.<img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-1738\" src=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/palabras-2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/palabras-2-300x200.jpg 300w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/palabras-2-768x512.jpg 768w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/palabras-2-628x419.jpg 628w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/03\/palabras-2.jpg 1050w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>La importancia de las palabras que utilizamos a la hora de hablar, son sobre todo importantes, aunque parezca lo contrario, para nosotros mismos, por lo que debemos ser conscientes del mensaje que queremos transmitir, la repercusi\u00f3n que va a tener en nosotros mismos, y escogerlas en base al resultado que queremos obtener.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Muchas veces he comentado en este blog la importancia de escoger bien las palabras para poder transmitir el mensaje adecuado, y hace unos d\u00edas un amigo me env\u00edo la siguiente tabla que me ha parecido interesante para poder resumir en ciertas frases hechas este asunto. Parto de la base de que utilizar la asertividad es [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1736","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/comments?post=1736"}],"version-history":[{"count":1,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1736\/revisions"}],"predecessor-version":[{"id":1739,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1736\/revisions\/1739"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/media?parent=1736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/categories?post=1736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/tags?post=1736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}