{"id":1755,"date":"2021-04-21T11:11:11","date_gmt":"2021-04-21T09:11:11","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/?p=1755"},"modified":"2021-04-21T11:11:11","modified_gmt":"2021-04-21T09:11:11","slug":"hacer-de-tu-hobby-tu-trabajo","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/2021\/04\/21\/hacer-de-tu-hobby-tu-trabajo\/","title":{"rendered":"Hacer de tu hobby tu trabajo"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Conseguir que tu hobby sea tu trabajo es el sue\u00f1o de muchos de nosotros y algo que muchos persiguen, claro que para esto hay que tener una <strong>afici\u00f3n<\/strong> verdadera, algo que nos entusiasma y en lo que podemos pasar muchas horas sin casi darnos cuenta y disfrutando del momento. Por de pronto, no todos tenemos un pasatiempo de este tipo, que llene nuestra vida de una forma plena con s\u00f3lo realizarla. Y cuando alguien logra que adem\u00e1s esta actividad le sirva como sustento econ\u00f3mico se puede decir que hace suya la famosa frase de Confuncio: \u201cElige un trabajo que te guste y no tendr\u00e1s que trabajar ni un d\u00eda de tu vida\u201d.<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1757\" src=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/04\/hobby-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/04\/hobby-200x300.jpg 200w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/04\/hobby.jpg 334w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n<p>Son pocos los afortunados que pueden trabajar en lo que les gusta, y menos a\u00fan lo que han logrado hacerlo a trav\u00e9s de desarrollar una idea de negocio con su hobby. Hay que destacar que la motivaci\u00f3n de estas personas para realizar su trabajo es muy superior a la de las otras, ya que no s\u00f3lo est\u00e1n trabajando para lograr un sueldo, sino que est\u00e1n realizando una actividad que les proporciona <strong>felicidad<\/strong> y por lo tanto les hace sentirse realizados de forma grata, aport\u00e1ndoles energ\u00eda y mejorando su autoestima y seguridad. Podemos decir que lograr que nuestro trabajo nos guste es algo que la mayor\u00eda de nosotros buscamos cuando pensamos en los estudios que queremos realizar, de forma que cuando vayamos a dar el salto al mundo laboral podamos trabajar en algo que nos guste. Pero no son muchos los afortunados que lo consiguen, y menos a\u00fan, los que pueden decir que han encontrado el trabajo dentro del mundo de su hobby.<img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-1758\" src=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/04\/hobby2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/04\/hobby2-300x200.jpg 300w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/04\/hobby2-768x512.jpg 768w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/04\/hobby2-628x419.jpg 628w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2021\/04\/hobby2.jpg 1050w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Pero hay que destacar, que estas personas probablemente disponen de valores a\u00f1adidos, por una parte, son valientes por dejarse guiar por su afici\u00f3n, y por otra, son emprendedores por desarrollar una idea de negocio entorno a esta, algo que no es f\u00e1cil de llevar a cabo, y menos que sea rentable como para lograr que te sustente econ\u00f3micamente durante tu vida laboral. Por otra parte, y quiz\u00e1 lo que podr\u00edamos considerar como aspecto de mejora en este tema, es que toda su vida la desarrollan alrededor de una misma actividad, por lo que los otros aspectos de su vida tambi\u00e9n deben estar muy cuidados para que en caso de que esta actividad tenga que cesar, la persona disponga de otros apoyos en lo que sustentar su vida y esta no se venga abajo. Es decir, si tenemos en cuenta que para tener una vida plena es conveniente disponer de varios apoyos que nos aporten seguridad y energ\u00eda, el conjugar una misma actividad de dos bases fundamentales corremos el riesgo de apostar mucho en una misma pr\u00e1ctica. Por esto, es importante disponer de otros soportes que nos proporcionen <strong>apoyo<\/strong> y seguridad.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Conseguir que tu hobby sea tu trabajo es el sue\u00f1o de muchos de nosotros y algo que muchos persiguen, claro que para esto hay que tener una afici\u00f3n verdadera, algo que nos entusiasma y en lo que podemos pasar muchas horas sin casi darnos cuenta y disfrutando del momento. Por de pronto, no todos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1755","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/comments?post=1755"}],"version-history":[{"count":2,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1755\/revisions"}],"predecessor-version":[{"id":1759,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1755\/revisions\/1759"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/media?parent=1755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/categories?post=1755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/tags?post=1755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}