{"id":1875,"date":"2022-01-12T10:42:51","date_gmt":"2022-01-12T09:42:51","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/?p=1875"},"modified":"2022-01-12T10:42:51","modified_gmt":"2022-01-12T09:42:51","slug":"nuevo-objetivo-volver-a-vivir-con-ilusion","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/2022\/01\/12\/nuevo-objetivo-volver-a-vivir-con-ilusion\/","title":{"rendered":"Nuevo objetivo: Volver a vivir con ilusi\u00f3n"},"content":{"rendered":"<p>Nuevo Objetivo: Volver a vivir<\/p>\n<p>Llevamos ya unos d\u00edas en el nuevo a\u00f1o y no hago mas que escuchar hablar sobre los nuevos retos y objetivos que nos proponemos para los siguientes meses. Algunas veces desde un punto de vista lleno de optimismo, creyendo con toda la fe que tenemos en nosotros mismo que vamos a ser capaces de conseguirlo, y otras veces con cierta amargura o incluso desde el humor, sabiendo que por muchos buenos prop\u00f3sitos que tengamos, nuestra vida y nuestros h\u00e1bitos no van a cambiar. Tambi\u00e9n he escuchado \u201ctrucos\u201d para conseguir aquello que m\u00e1s queremos, algo de los que yo misma he escrito muchos a\u00f1os en esta \u00e9poca, animando a que podamos sentirnos mejor logrando cambiar esos aspectos de mejora o logrando los retos que tenemos.<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1876\" src=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/01\/navitris-200x300.jpeg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/01\/navitris-200x300.jpeg 200w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/01\/navitris-768x1154.jpeg 768w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/01\/navitris-418x628.jpeg 418w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/01\/navitris.jpeg 865w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n<p>Pero este a\u00f1o, y con todo lo que estamos viviendo en las \u00faltimas semanas, tengo que admitir, que lo \u00fanico que quiero es volver a recuperar la vida que ten\u00edamos, con eso me conformo, y ya dejo para otro a\u00f1o lo de cambiar los aspectos de mejora. S\u00e9 que puede resultar conformista, pero cuando cre\u00edamos que \u00edbamos a recuperar las Navidades y que las fiestas las \u00edbamos a poder disfrutar con nuestros seres queridos, ha llegado un tsunami que se ha llevado por delante todas nuestras esperanzas, haciendo que estas fiestas hayan sido a\u00fan m\u00e1s duras que las anteriores. A lo mejor porque no lo esper\u00e1bamos, o bien porque en la mayor\u00eda de casas hab\u00eda uno o varios positivos, estas Navidades tampoco las hemos podido disfrutar y la frustraci\u00f3n y desesperaci\u00f3n ha sido mayor.<img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-1877\" src=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/01\/navitriste-jpeg-206x300.jpeg\" alt=\"\" width=\"206\" height=\"300\" srcset=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/01\/navitriste-jpeg-206x300.jpeg 206w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/01\/navitriste-jpeg-768x1117.jpeg 768w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/01\/navitriste-jpeg-432x628.jpeg 432w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/01\/navitriste-jpeg.jpeg 894w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/><\/p>\n<p>Por este motivo, quiero aprovechar este post para dar \u00e1nimos y esperanza de que poco a poco podemos volver a recuperar nuestras vidas, aunque sea a\u00f1adiendo a nuestra lista de enfermedades el covid, y aprendamos a vivir con ello. Espero que en pocas semanas la situaci\u00f3n actual mejore, y quiero creer lo que algunos vir\u00f3logos opinan sobre que es el principio del fin. Y desde esta perspectiva empezar a sentirnos mejor hoy mismo para poder superar esta nueva etapa. Si no es as\u00ed, no nos preocupemos antes de tiempo, porque seguro que en el momento encontramos la forma de superarlo, recordemos los \u00faltimos meses, casi dos a\u00f1os, y lo fuertes que hemos sido, y que la esperanza es lo que nos da fuerza para continuar. Sea como sea hay que pasarlo, y cuanto mejor lo pasemos m\u00e1s tranquilos y de mejor \u00e1nimo vamos a estar. Y al igual que los d\u00edas se alargan, que crezca nuestra <strong>ilusi\u00f3n<\/strong> por vivir.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Nuevo Objetivo: Volver a vivir Llevamos ya unos d\u00edas en el nuevo a\u00f1o y no hago mas que escuchar hablar sobre los nuevos retos y objetivos que nos proponemos para los siguientes meses. Algunas veces desde un punto de vista lleno de optimismo, creyendo con toda la fe que tenemos en nosotros mismo que vamos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1875","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/comments?post=1875"}],"version-history":[{"count":1,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1875\/revisions"}],"predecessor-version":[{"id":1878,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1875\/revisions\/1878"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/media?parent=1875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/categories?post=1875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/tags?post=1875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}