{"id":1914,"date":"2022-05-18T22:53:46","date_gmt":"2022-05-18T20:53:46","guid":{"rendered":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/?p=1914"},"modified":"2022-05-18T23:08:30","modified_gmt":"2022-05-18T21:08:30","slug":"cuando-las-malas-noticias-te-rodean","status":"publish","type":"post","link":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/2022\/05\/18\/cuando-las-malas-noticias-te-rodean\/","title":{"rendered":"Cuando las malas noticias te rodean"},"content":{"rendered":"<p>Llevamos m\u00e1s de dos a\u00f1os sumergidos en una situaci\u00f3n cuanto menos complicada y que en ning\u00fan caso nos la esper\u00e1bamos. Hemos ido asumiendo diferentes situaciones, diferentes formas de vivir y teniendo que afrontar acontecimientos que nunca hubi\u00e9ramos imaginado, y frente a ello hemos sido fuertes y valientes. Aunque ha habido momentos en los que nos hemos podido desmotivar y en los que hemos podido pensar que no \u00edbamos a ser capaces de salir bien de esta situaci\u00f3n, hemos conseguido llegar hasta aqu\u00ed, a pesar de haber cargado secuelas en nuestra mochila que debemos aprender a gestionar para ir deshaci\u00e9ndonos de ellas.<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1916\" src=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/05\/malas-noticias-300x113.jpg\" alt=\"\" width=\"300\" height=\"113\" srcset=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/05\/malas-noticias-300x113.jpg 300w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/05\/malas-noticias.jpg 564w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Adem\u00e1s, en las \u00faltimas semanas nos hemos encontrado con noticias a\u00fan m\u00e1s sorprendentes que cuando parec\u00eda que est\u00e1bamos terminando con una pesadilla se nos ha venido otra encima. Incluso, esta nueva situaci\u00f3n, la guerra, la estamos normalizando porque no siendo tan cercana estamos aprendiendo a vivir con ella. Sin embargo, esto no quita para que no nos pese y que viendo las noticias sintamos un gran pesar por aquellos que lo est\u00e1n pasando mucho peor que nosotros y por no poder entender c\u00f3mo se ha podido llegar a esta situaci\u00f3n. Y encima, la vida contin\u00faa, y a nuestro alrededor van sucediendo cosas que no son agradables y que nos hacen tener que ser fuertes. Las cosas que van sucediendo las tenemos que afrontar junto a todo lo que tenemos que gestionar de los dos \u00faltimos a\u00f1os, y todo esto sabiendo que la mejor de las actitudes es la de aprovechar cada momento y cada instante aprendiendo a vivirlo y a disfrutarlo de \u00a0una forma plena.<\/p>\n<p>Y en esto estamos cuando adem\u00e1s nos enteramos de alguna desgracia que le ha pasado a un amigo cercano y que nos hacen pensar que tenemos y que debemos aprovechar cada minuto y cada instante de nuestra vida. Son situaciones que nos hacen valorar qu\u00e9 es lo verdaderamente importante y quedarnos con aquellas peque\u00f1as cosas que nos hacen felices.<img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-1915\" src=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/05\/tecnicas-como-la-meditacion-la-respiracion-consciente-y-el-yoga-ayudan-a-la-salud-fisica-y-mental-1160690-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/05\/tecnicas-como-la-meditacion-la-respiracion-consciente-y-el-yoga-ayudan-a-la-salud-fisica-y-mental-1160690-300x169.jpg 300w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/05\/tecnicas-como-la-meditacion-la-respiracion-consciente-y-el-yoga-ayudan-a-la-salud-fisica-y-mental-1160690-768x432.jpg 768w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/05\/tecnicas-como-la-meditacion-la-respiracion-consciente-y-el-yoga-ayudan-a-la-salud-fisica-y-mental-1160690-628x353.jpg 628w, https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-content\/uploads\/sites\/62\/2022\/05\/tecnicas-como-la-meditacion-la-respiracion-consciente-y-el-yoga-ayudan-a-la-salud-fisica-y-mental-1160690.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Por todo esto, quiero animar a todas las personas que lo est\u00e9n pasando mal por algo personal o por un asunto concerniente a un ser querido, a tomar una actitud positiva que, aunque s\u00e9 que no es f\u00e1cil, es la forma m\u00e1s sencilla y c\u00f3moda de afrontar las penurias. Pensemos que somos capaces de salir de la situaci\u00f3n que debamos afrontar y que lo vamos a hacer reforzados, porque si algo hemos aprendido es que somos m\u00e1s fuertes de lo que pens\u00e1bamos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Llevamos m\u00e1s de dos a\u00f1os sumergidos en una situaci\u00f3n cuanto menos complicada y que en ning\u00fan caso nos la esper\u00e1bamos. Hemos ido asumiendo diferentes situaciones, diferentes formas de vivir y teniendo que afrontar acontecimientos que nunca hubi\u00e9ramos imaginado, y frente a ello hemos sido fuertes y valientes. Aunque ha habido momentos en los que nos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":93,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1914","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/comments?post=1914"}],"version-history":[{"count":1,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1914\/revisions"}],"predecessor-version":[{"id":1917,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/posts\/1914\/revisions\/1917"}],"wp:attachment":[{"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/media?parent=1914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/categories?post=1914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.diariovasco.com\/trampolin-vida\/wp-json\/wp\/v2\/tags?post=1914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}